{"id":7876,"date":"2019-04-25T22:54:30","date_gmt":"2019-04-25T18:54:30","guid":{"rendered":"http:\/\/www.cidademarketing.com.br\/marketing\/?p=7876"},"modified":"2019-04-25T22:54:32","modified_gmt":"2019-04-25T18:54:32","slug":"carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/","title":{"rendered":"Carlos Ghosn, ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, \u00e9 liberado pela segunda vez ap\u00f3s pagar fian\u00e7a de US$ 4 milh\u00f5es"},"content":{"rendered":"\n<p>\n\nO Tribunal Distrital de T\u00f3quio concedeu liberdade sob fian\u00e7a, pela segunda vez, ao ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, Carlos Ghosn, nesta quinta-feira (25).<\/p>\n\n\n\n<p>Ghosn havia sido liberado no dia 6 de mar\u00e7o, depois de passar 108 dias em deten\u00e7\u00e3o, pagando uma fian\u00e7a no valor de US$ 9 milh\u00f5es, mas foi preso novamente no dia 4 de abril.<\/p>\n\n\n\n<p>O tribunal determinou uma fian\u00e7a adicional no valor de US$ 4 milh\u00f5es.<\/p>\n\n\n\n<p>Os promotores devem recorrer \u00e0 decis\u00e3o da corte de conceder liberdade a Ghosn. Caso o tribunal rejeite o recurso e Ghosn pague a fian\u00e7a, ele poder\u00e1 sair do Centro de Deten\u00e7\u00e3o de T\u00f3quio ainda hoje. <\/p>\n\n\n\n<p>CidadeMarketing com informa\u00e7\u00f5es da <a href=\"http:\/\/agenciabrasil.ebc.com.br\/internacional\/noticia\/2019-04\/tribunal-de-toquio-concede-liberdade-ghosn-pela-segunda-vez\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"EBC (abre numa nova aba)\">EBC<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal Distrital de T\u00f3quio concedeu liberdade sob fian\u00e7a, pela segunda vez, ao ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, Carlos Ghosn, nesta quinta-feira (25). Ghosn havia sido liberado no dia 6 de mar\u00e7o, depois de passar 108 dias em deten\u00e7\u00e3o, pagando uma fian\u00e7a no valor de US$ 9 milh\u00f5es, mas foi preso novamente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6],"tags":[147,691,195,316],"class_list":["post-7876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-brasil","tag-carlos-ghosn","tag-lideranca","tag-nissan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carlos Ghosn, ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, \u00e9 liberado pela segunda vez ap\u00f3s pagar fian\u00e7a de US$ 4 milh\u00f5es - CidadeMarketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carlos Ghosn, ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, \u00e9 liberado pela segunda vez ap\u00f3s pagar fian\u00e7a de US$ 4 milh\u00f5es - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"O Tribunal Distrital de T\u00f3quio concedeu liberdade sob fian\u00e7a, pela segunda vez, ao ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, Carlos Ghosn, nesta quinta-feira (25). Ghosn havia sido liberado no dia 6 de mar\u00e7o, depois de passar 108 dias em deten\u00e7\u00e3o, pagando uma fian\u00e7a no valor de US$ 9 milh\u00f5es, mas foi preso novamente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-25T18:54:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-25T18:54:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2018\/11\/CARLOS_GHOSN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"Carlos Ghosn, ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, \u00e9 liberado pela segunda vez ap\u00f3s pagar fian\u00e7a de US$ 4 milh\u00f5es\",\"datePublished\":\"2019-04-25T18:54:30+00:00\",\"dateModified\":\"2019-04-25T18:54:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/\"},\"wordCount\":143,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/CARLOS_GHOSN.jpg\",\"keywords\":[\"Brasil\",\"Carlos Ghosn\",\"lideran\u00e7a\",\"Nissan\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/\",\"name\":\"Carlos Ghosn, ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, \u00e9 liberado pela segunda vez ap\u00f3s pagar fian\u00e7a de US$ 4 milh\u00f5es - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/CARLOS_GHOSN.jpg\",\"datePublished\":\"2019-04-25T18:54:30+00:00\",\"dateModified\":\"2019-04-25T18:54:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/CARLOS_GHOSN.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/CARLOS_GHOSN.jpg\",\"width\":799,\"height\":1200,\"caption\":\"Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2019\\\/04\\\/25\\\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carlos Ghosn, ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, \u00e9 liberado pela segunda vez ap\u00f3s pagar fian\u00e7a de US$ 4 milh\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carlos Ghosn, ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, \u00e9 liberado pela segunda vez ap\u00f3s pagar fian\u00e7a de US$ 4 milh\u00f5es - CidadeMarketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Carlos Ghosn, ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, \u00e9 liberado pela segunda vez ap\u00f3s pagar fian\u00e7a de US$ 4 milh\u00f5es - CidadeMarketing","og_description":"O Tribunal Distrital de T\u00f3quio concedeu liberdade sob fian\u00e7a, pela segunda vez, ao ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, Carlos Ghosn, nesta quinta-feira (25). Ghosn havia sido liberado no dia 6 de mar\u00e7o, depois de passar 108 dias em deten\u00e7\u00e3o, pagando uma fian\u00e7a no valor de US$ 9 milh\u00f5es, mas foi preso novamente [&hellip;]","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2019-04-25T18:54:30+00:00","article_modified_time":"2019-04-25T18:54:32+00:00","og_image":[{"width":799,"height":1200,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2018\/11\/CARLOS_GHOSN.jpg","type":"image\/jpeg"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"Carlos Ghosn, ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, \u00e9 liberado pela segunda vez ap\u00f3s pagar fian\u00e7a de US$ 4 milh\u00f5es","datePublished":"2019-04-25T18:54:30+00:00","dateModified":"2019-04-25T18:54:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/"},"wordCount":143,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2018\/11\/CARLOS_GHOSN.jpg","keywords":["Brasil","Carlos Ghosn","lideran\u00e7a","Nissan"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/","name":"Carlos Ghosn, ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, \u00e9 liberado pela segunda vez ap\u00f3s pagar fian\u00e7a de US$ 4 milh\u00f5es - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2018\/11\/CARLOS_GHOSN.jpg","datePublished":"2019-04-25T18:54:30+00:00","dateModified":"2019-04-25T18:54:32+00:00","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2018\/11\/CARLOS_GHOSN.jpg","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2018\/11\/CARLOS_GHOSN.jpg","width":799,"height":1200,"caption":"Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2019\/04\/25\/carlos-ghosn-ex-presidente-do-conselho-de-administracao-da-nissan-motor-e-liberado-pela-segunda-vez-apos-pagar-fianca-de-us-4-milhoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"Carlos Ghosn, ex-presidente do Conselho de Administra\u00e7\u00e3o da Nissan Motor, \u00e9 liberado pela segunda vez ap\u00f3s pagar fian\u00e7a de US$ 4 milh\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/7876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=7876"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/7876\/revisions"}],"predecessor-version":[{"id":7877,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/7876\/revisions\/7877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/3174"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=7876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=7876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=7876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}