{"id":58933,"date":"2026-01-12T10:34:37","date_gmt":"2026-01-12T13:34:37","guid":{"rendered":"https:\/\/www.cidademarketing.com.br\/marketing\/?p=58933"},"modified":"2026-01-12T10:34:37","modified_gmt":"2026-01-12T13:34:37","slug":"elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/","title":{"rendered":"Elo lan\u00e7a campanha com Wagner Moura ap\u00f3s vit\u00f3ria hist\u00f3rica no Globo de Ouro"},"content":{"rendered":"<p>Em um momento em que o Brasil ganha proje\u00e7\u00e3o in\u00e9dita no cinema internacional, a Elo refor\u00e7a seu posicionamento como marca brasileira. A empresa de tecnologia de pagamentos, que completa 15 anos em 2026, lan\u00e7ou neste domingo uma nova campanha institucional estrelada por Wagner Moura, aprofundando uma estrat\u00e9gia iniciada em 2023 ao apostar na brasilidade como diferencial em um mercado dominado por bandeiras globais.<\/p>\n<p>O ator, que volta \u00e0 publicidade nacional ap\u00f3s 13 anos, protagoniza um filme veiculado a partir deste domingo (11) em todas as m\u00eddias. No v\u00eddeo, Wagner Moura, baiano e premiado mundialmente, senta-se em uma cadeira para contar quem ele \u00e9. Em tom \u00edntimo, constr\u00f3i uma narrativa sobre identidade e pertencimento: mostra uma fotografia de quando era crian\u00e7a no sert\u00e3o nordestino, relembra suas origens e, ao final, encerra o filme sambando \u2014 gesto simb\u00f3lico que traduz leveza, orgulho e conex\u00e3o com a cultura brasileira.<\/p>\n<div class=\"youtube-embed\" data-video_id=\"88YnvYBDF4g\"><iframe title=\"Onde tem um brasileiro, tem a nossa torcida.\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/88YnvYBDF4g?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>A escolha de Wagner Moura ganha ainda mais for\u00e7a diante do momento hist\u00f3rico vivido pelo pa\u00eds. No Globo de Ouro 2026, O Agente Secreto conquistou o pr\u00eamio de Melhor Filme de L\u00edngua N\u00e3o-Inglesa, enquanto o pr\u00f3prio Wagner Moura, aos 49 anos, venceu a categoria de Melhor Ator em Filme de Drama. A consagra\u00e7\u00e3o internacional amplia o peso simb\u00f3lico da campanha e conecta a Elo a um dos maiores orgulhos recentes da cultura nacional.<\/p>\n<p>Ao unir a trajet\u00f3ria pessoal do ator \u00e0 proposta da marca, a Elo constr\u00f3i uma narrativa que vai al\u00e9m da publicidade tradicional. O filme n\u00e3o fala apenas de meios de pagamento, mas de identidade, origem e pertencimento. Em um cen\u00e1rio globalizado, no qual gigantes internacionais dominam o setor, a empresa aposta na autenticidade como ativo estrat\u00e9gico: ser brasileira n\u00e3o como limita\u00e7\u00e3o, mas como diferencial competitivo.<\/p>\n<p>A campanha dialoga diretamente com o clima emocional do pa\u00eds \u2014 entre o reconhecimento mundial no cinema. Com Wagner Moura, a empresa transforma a brasilidade em discurso de marca e reafirma seu lugar em uma conversa maior: a de um pa\u00eds que busca se ver representado, reconhecido e orgulhoso de si mesmo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em um momento em que o Brasil ganha proje\u00e7\u00e3o in\u00e9dita no cinema internacional, a Elo refor\u00e7a seu posicionamento como marca brasileira. A empresa de tecnologia de pagamentos, que completa 15 anos em 2026, lan\u00e7ou neste domingo uma nova campanha institucional estrelada por Wagner Moura, aprofundando uma estrat\u00e9gia iniciada em 2023 ao apostar na brasilidade como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":58934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6,14],"tags":[65,11515,11522,11518,11519,11526,11514,8626,11521,28,11524,11517,11520,11523,11516,11525,11513,11505],"class_list":["post-58933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-videos","tag-campanha","tag-campanha-elo-2026","tag-campanha-institucional-elo","tag-cartao-elo-campanha","tag-cinema-brasileiro-internacional","tag-elo-15-anos","tag-elo-wagner-moura","tag-globo-de-ouro","tag-marca-brasileira-elo","tag-marketing","tag-marketing-de-brasilidade","tag-marketing-elo-brasilidade","tag-o-agente-secreto-globo-de-ouro","tag-orgulho-nacional-publicidade","tag-publicidade-elo","tag-retorno-wagner-moura-publicidade","tag-wagner-moura","tag-wagner-moura-globo-de-ouro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elo lan\u00e7a campanha com Wagner Moura ap\u00f3s vit\u00f3ria hist\u00f3rica no Globo de Ouro - CidadeMarketing<\/title>\n<meta name=\"description\" content=\"A Elo lan\u00e7a campanha institucional com Wagner Moura, rec\u00e9m-premiado no Globo de Ouro. A a\u00e7\u00e3o refor\u00e7a a brasilidade da marca em um mercado dominado por bandeiras globais e celebra a identidade nacional em um momento hist\u00f3rico para o cinema brasileiro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elo lan\u00e7a campanha com Wagner Moura ap\u00f3s vit\u00f3ria hist\u00f3rica no Globo de Ouro - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"A Elo lan\u00e7a campanha institucional com Wagner Moura, rec\u00e9m-premiado no Globo de Ouro. A a\u00e7\u00e3o refor\u00e7a a brasilidade da marca em um mercado dominado por bandeiras globais e celebra a identidade nacional em um momento hist\u00f3rico para o cinema brasileiro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-12T13:34:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2026\/01\/elo_campanha_wagnermoura_globodeouro.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1166\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"Elo lan\u00e7a campanha com Wagner Moura ap\u00f3s vit\u00f3ria hist\u00f3rica no Globo de Ouro\",\"datePublished\":\"2026-01-12T13:34:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/\"},\"wordCount\":383,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/elo_campanha_wagnermoura_globodeouro.webp\",\"keywords\":[\"campanha\",\"campanha Elo 2026\",\"campanha institucional Elo\",\"cart\u00e3o Elo campanha\",\"cinema brasileiro internacional\",\"Elo 15 anos\",\"Elo Wagner Moura\",\"Globo de Ouro\",\"marca brasileira Elo\",\"marketing\",\"marketing de brasilidade\",\"marketing Elo brasilidade\",\"O Agente Secreto Globo de Ouro\",\"orgulho nacional publicidade\",\"publicidade Elo\",\"retorno Wagner Moura publicidade\",\"Wagner Moura\",\"Wagner Moura Globo de Ouro\"],\"articleSection\":[\"Not\u00edcias\",\"Videos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/\",\"name\":\"Elo lan\u00e7a campanha com Wagner Moura ap\u00f3s vit\u00f3ria hist\u00f3rica no Globo de Ouro - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/elo_campanha_wagnermoura_globodeouro.webp\",\"datePublished\":\"2026-01-12T13:34:37+00:00\",\"description\":\"A Elo lan\u00e7a campanha institucional com Wagner Moura, rec\u00e9m-premiado no Globo de Ouro. A a\u00e7\u00e3o refor\u00e7a a brasilidade da marca em um mercado dominado por bandeiras globais e celebra a identidade nacional em um momento hist\u00f3rico para o cinema brasileiro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/elo_campanha_wagnermoura_globodeouro.webp\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/elo_campanha_wagnermoura_globodeouro.webp\",\"width\":1166,\"height\":648,\"caption\":\"Reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2026\\\/01\\\/12\\\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elo lan\u00e7a campanha com Wagner Moura ap\u00f3s vit\u00f3ria hist\u00f3rica no Globo de Ouro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elo lan\u00e7a campanha com Wagner Moura ap\u00f3s vit\u00f3ria hist\u00f3rica no Globo de Ouro - CidadeMarketing","description":"A Elo lan\u00e7a campanha institucional com Wagner Moura, rec\u00e9m-premiado no Globo de Ouro. A a\u00e7\u00e3o refor\u00e7a a brasilidade da marca em um mercado dominado por bandeiras globais e celebra a identidade nacional em um momento hist\u00f3rico para o cinema brasileiro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/","og_locale":"pt_BR","og_type":"article","og_title":"Elo lan\u00e7a campanha com Wagner Moura ap\u00f3s vit\u00f3ria hist\u00f3rica no Globo de Ouro - CidadeMarketing","og_description":"A Elo lan\u00e7a campanha institucional com Wagner Moura, rec\u00e9m-premiado no Globo de Ouro. A a\u00e7\u00e3o refor\u00e7a a brasilidade da marca em um mercado dominado por bandeiras globais e celebra a identidade nacional em um momento hist\u00f3rico para o cinema brasileiro.","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2026-01-12T13:34:37+00:00","og_image":[{"width":1166,"height":648,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2026\/01\/elo_campanha_wagnermoura_globodeouro.webp","type":"image\/webp"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"Elo lan\u00e7a campanha com Wagner Moura ap\u00f3s vit\u00f3ria hist\u00f3rica no Globo de Ouro","datePublished":"2026-01-12T13:34:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/"},"wordCount":383,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2026\/01\/elo_campanha_wagnermoura_globodeouro.webp","keywords":["campanha","campanha Elo 2026","campanha institucional Elo","cart\u00e3o Elo campanha","cinema brasileiro internacional","Elo 15 anos","Elo Wagner Moura","Globo de Ouro","marca brasileira Elo","marketing","marketing de brasilidade","marketing Elo brasilidade","O Agente Secreto Globo de Ouro","orgulho nacional publicidade","publicidade Elo","retorno Wagner Moura publicidade","Wagner Moura","Wagner Moura Globo de Ouro"],"articleSection":["Not\u00edcias","Videos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/","name":"Elo lan\u00e7a campanha com Wagner Moura ap\u00f3s vit\u00f3ria hist\u00f3rica no Globo de Ouro - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2026\/01\/elo_campanha_wagnermoura_globodeouro.webp","datePublished":"2026-01-12T13:34:37+00:00","description":"A Elo lan\u00e7a campanha institucional com Wagner Moura, rec\u00e9m-premiado no Globo de Ouro. A a\u00e7\u00e3o refor\u00e7a a brasilidade da marca em um mercado dominado por bandeiras globais e celebra a identidade nacional em um momento hist\u00f3rico para o cinema brasileiro.","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2026\/01\/elo_campanha_wagnermoura_globodeouro.webp","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2026\/01\/elo_campanha_wagnermoura_globodeouro.webp","width":1166,"height":648,"caption":"Reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2026\/01\/12\/elo-lanca-campanha-com-wagner-moura-apos-vitoria-historica-no-globo-de-ouro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"Elo lan\u00e7a campanha com Wagner Moura ap\u00f3s vit\u00f3ria hist\u00f3rica no Globo de Ouro"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/58933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=58933"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/58933\/revisions"}],"predecessor-version":[{"id":58935,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/58933\/revisions\/58935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/58934"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=58933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=58933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=58933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}