{"id":57315,"date":"2025-08-20T13:18:16","date_gmt":"2025-08-20T16:18:16","guid":{"rendered":"https:\/\/www.cidademarketing.com.br\/marketing\/?p=57315"},"modified":"2025-08-20T13:18:16","modified_gmt":"2025-08-20T16:18:16","slug":"tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/","title":{"rendered":"T\u00eanis: SP Open confirma jovens promessas brasileiras na chave principal"},"content":{"rendered":"<p>O SP Open anunciou nesta segunda-feira (18) os dois primeiros convites para a chave principal de simples: as jovens tenistas Victoria Barros e Nauhany Silva, ambas com 15 anos, que se juntam \u00e0s brasileiras Beatriz Haddad Maia e Laura Pigossi no torneio que marca o retorno de S\u00e3o Paulo ao calend\u00e1rio da WTA ap\u00f3s 25 anos. O evento acontece entre os dias 6 e 14 de setembro, no Parque Villa-Lobos, na capital paulista.<\/p>\n<p>Natural de Natal (RN), Victoria Barros \u00e9 considerada um dos principais nomes da nova gera\u00e7\u00e3o do t\u00eanis mundial. Conhecida pelo estilo de jogo agressivo, come\u00e7ou a competir no circuito juvenil aos 13 anos, em 2023, ano em que conquistou quatro de seus cinco t\u00edtulos em torneios ITF.<\/p>\n<p>Em 2024, garantiu o maior t\u00edtulo da carreira at\u00e9 o momento, no J300 de Bamberg, na Alemanha, e passou a figurar entre as 25 melhores juvenis do mundo. No mesmo ano, fez sua estreia no circuito profissional, alcan\u00e7ando a semifinal do W15 de Monastir, na Tun\u00edsia, e conquistando seus primeiros pontos na WTA.<\/p>\n<p>Desde 2023, Victoria treina sob a supervis\u00e3o de Patrick Mouratoglou, ex-t\u00e9cnico de Serena Williams, e disputar\u00e1 no SP Open o seu primeiro WTA 250.<\/p>\n<p>\u201cEstou muito feliz em poder participar do meu primeiro WTA e justamente em casa, no Brasil, com a torcida e as pessoas que gostam de mim. Vai ser uma experi\u00eancia incr\u00edvel, estou super preparada e sei que vou me divertir muito\u201d, afirmou a potiguar, apelidada de Victorinha.<\/p>\n<p>A paulistana Nauhany Silva, conhecida como Nan\u00e1, tamb\u00e9m chega ao torneio como grande promessa do t\u00eanis nacional. Aos 13 anos, surpreendeu ao vencer o J30 da Guatemala, torneio at\u00e9 18 anos, e em 2024 entrou para a hist\u00f3ria como a primeira jogadora nascida em 2010 a entrar no ranking da WTA.<\/p>\n<p>Atualmente entre as 40 melhores juvenis do mundo, Nan\u00e1 soma quatro t\u00edtulos de ITF, incluindo o J200 de Assun\u00e7\u00e3o, al\u00e9m de ter alcan\u00e7ado as oitavas de final na chave juvenil de Wimbledon este ano.<\/p>\n<p>\u201cEstou muito feliz em jogar um torneio deste n\u00edvel em casa. \u00c9 muito gratificante poder jogar com a minha fam\u00edlia e meus amigos me apoiando, vai ser uma semana muito especial, ainda mais em um lugar como o Villa-Lobos, onde eu jogava quando era menor\u201d, disse a jovem.<\/p>\n<p>Al\u00e9m das promessas brasileiras, o torneio contar\u00e1 com nomes internacionais como Alex Eala, Hailey Baptiste e Ajla Tomljanovic. A chave principal ainda ter\u00e1 dois convites adicionais e quatro jogadoras vindas do qualifying, programado para os dias 6 e 7 de setembro, tamb\u00e9m no Parque Villa-Lobos, com entrada gratuita mediante retirada pr\u00e9via de ingressos.<\/p>\n<p>\u201cVai ser uma oportunidade \u00fanica do p\u00fablico ver em primeira m\u00e3o o futuro do t\u00eanis feminino, assim como ser\u00e1 especial para elas jogarem o primeiro WTA da carreira ao lado da fam\u00edlia e amigos. Tor\u00e7o para que aproveitem essa experi\u00eancia e usem o SP Open para acelerar a transi\u00e7\u00e3o para o circuito profissional\u201d, destacou Luiz Carvalho, diretor do SP Open.<\/p>\n<p>Os ingressos Ground Pass j\u00e1 est\u00e3o \u00e0 venda no <a href=\"https:\/\/www.eventim.com.br\/campaign\/sp-open\" target=\"_blank\" rel=\"noopener\">site da Eventim<\/a> e d\u00e3o acesso ao Espa\u00e7o Boulevard, que re\u00fane op\u00e7\u00f5es gastron\u00f4micas, ativa\u00e7\u00f5es de patrocinadores, lojas oficiais e um tel\u00e3o interativo. O p\u00fablico tamb\u00e9m poder\u00e1 acompanhar treinos e jogos nas quadras secund\u00e1rias, conforme a programa\u00e7\u00e3o e a capacidade do local.<\/p>\n<figure id=\"attachment_57318\" aria-describedby=\"caption-attachment-57318\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-57318 size-full\" src=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Victoria_Barros_tenista.webp\" alt=\"Elas se juntam a Bia Haddad Maia e Laura Pigossi na disputa do WTA da maior cidade das Am\u00e9ricas\" width=\"1000\" height=\"667\" srcset=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Victoria_Barros_tenista.webp 1000w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Victoria_Barros_tenista-300x200.webp 300w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Victoria_Barros_tenista-768x512.webp 768w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Victoria_Barros_tenista-630x420.webp 630w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Victoria_Barros_tenista-640x427.webp 640w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Victoria_Barros_tenista-681x454.webp 681w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-57318\" class=\"wp-caption-text\">Victoria Barros (Divulga\u00e7\u00e3o\/CBT)<\/figcaption><\/figure>\n<p>O SP Open conta com patroc\u00ednio m\u00e1ster de Claro e Heineken 0.0, al\u00e9m de ALLOS, Shopping VillaLobos e BRB. Tamb\u00e9m apoiam o evento marcas como Prudential, Atvos, B3, Seara Gourmet, Tegra, Engie, Oncocl\u00ednicas, Faixa Azul, EMS, World Wine, Revo, Zetaflex, BlueFit Academias, Melitta e Giovanna Baby.<\/p>\n<p>As marcas esportivas oficiais s\u00e3o Slyce e ASICS, com Wilson como fornecedora de bolas. O torneio \u00e9 realizado pela IMM, promovido pelo ICT e conta com incentivo do Minist\u00e9rio do Esporte, via Lei de Incentivo ao Esporte, al\u00e9m do apoio da Prefeitura de S\u00e3o Paulo\/SPTuris.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O SP Open anunciou nesta segunda-feira (18) os dois primeiros convites para a chave principal de simples: as jovens tenistas Victoria Barros e Nauhany Silva, ambas com 15 anos, que se juntam \u00e0s brasileiras Beatriz Haddad Maia e Laura Pigossi no torneio que marca o retorno de S\u00e3o Paulo ao calend\u00e1rio da WTA ap\u00f3s 25 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":57319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6],"tags":[6098,9712,9711,656,9222,9420,8614,9710,8991],"class_list":["post-57315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-bia-haddad","tag-ingressos-sp-open","tag-nauhany-silva","tag-sao-paulo","tag-sp-open","tag-sp-open-2025","tag-tenistas","tag-victoria-barros","tag-wta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00eanis: SP Open confirma jovens promessas brasileiras na chave principal - CidadeMarketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00eanis: SP Open confirma jovens promessas brasileiras na chave principal - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"O SP Open anunciou nesta segunda-feira (18) os dois primeiros convites para a chave principal de simples: as jovens tenistas Victoria Barros e Nauhany Silva, ambas com 15 anos, que se juntam \u00e0s brasileiras Beatriz Haddad Maia e Laura Pigossi no torneio que marca o retorno de S\u00e3o Paulo ao calend\u00e1rio da WTA ap\u00f3s 25 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-20T16:18:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Nauhany_Silva-_tenista.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"T\u00eanis: SP Open confirma jovens promessas brasileiras na chave principal\",\"datePublished\":\"2025-08-20T16:18:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/\"},\"wordCount\":686,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Nauhany_Silva-_tenista.webp\",\"keywords\":[\"Bia Haddad\",\"ingressos SP Open\",\"Nauhany Silva\",\"S\u00e3o Paulo\",\"SP Open\",\"SP Open 2025\",\"tenistas\",\"Victoria Barros\",\"WTA\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/\",\"name\":\"T\u00eanis: SP Open confirma jovens promessas brasileiras na chave principal - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Nauhany_Silva-_tenista.webp\",\"datePublished\":\"2025-08-20T16:18:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Nauhany_Silva-_tenista.webp\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Nauhany_Silva-_tenista.webp\",\"width\":1000,\"height\":667,\"caption\":\"Nauhany Silva (Divulga\u00e7\u00e3o\\\/CBT)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2025\\\/08\\\/20\\\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00eanis: SP Open confirma jovens promessas brasileiras na chave principal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00eanis: SP Open confirma jovens promessas brasileiras na chave principal - CidadeMarketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/","og_locale":"pt_BR","og_type":"article","og_title":"T\u00eanis: SP Open confirma jovens promessas brasileiras na chave principal - CidadeMarketing","og_description":"O SP Open anunciou nesta segunda-feira (18) os dois primeiros convites para a chave principal de simples: as jovens tenistas Victoria Barros e Nauhany Silva, ambas com 15 anos, que se juntam \u00e0s brasileiras Beatriz Haddad Maia e Laura Pigossi no torneio que marca o retorno de S\u00e3o Paulo ao calend\u00e1rio da WTA ap\u00f3s 25 [&hellip;]","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2025-08-20T16:18:16+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Nauhany_Silva-_tenista.webp","type":"image\/webp"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"T\u00eanis: SP Open confirma jovens promessas brasileiras na chave principal","datePublished":"2025-08-20T16:18:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/"},"wordCount":686,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Nauhany_Silva-_tenista.webp","keywords":["Bia Haddad","ingressos SP Open","Nauhany Silva","S\u00e3o Paulo","SP Open","SP Open 2025","tenistas","Victoria Barros","WTA"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/","name":"T\u00eanis: SP Open confirma jovens promessas brasileiras na chave principal - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Nauhany_Silva-_tenista.webp","datePublished":"2025-08-20T16:18:16+00:00","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Nauhany_Silva-_tenista.webp","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2025\/08\/Nauhany_Silva-_tenista.webp","width":1000,"height":667,"caption":"Nauhany Silva (Divulga\u00e7\u00e3o\/CBT)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2025\/08\/20\/tenis-sp-open-confirma-jovens-promessas-brasileiras-na-chave-principal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"T\u00eanis: SP Open confirma jovens promessas brasileiras na chave principal"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/57315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=57315"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/57315\/revisions"}],"predecessor-version":[{"id":57320,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/57315\/revisions\/57320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/57319"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=57315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=57315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=57315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}