{"id":46235,"date":"2023-07-19T10:05:49","date_gmt":"2023-07-19T13:05:49","guid":{"rendered":"https:\/\/www.cidademarketing.com.br\/marketing\/?p=46235"},"modified":"2023-07-19T10:05:49","modified_gmt":"2023-07-19T13:05:49","slug":"banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/","title":{"rendered":"Banco do Brasil lan\u00e7a campanha inovadora focada em seguran\u00e7a e prote\u00e7\u00e3o financeira"},"content":{"rendered":"<p>Seguran\u00e7a \u00e9 a palavra da vez. De acordo com a Federa\u00e7\u00e3o Brasileira de Bancos (Febraban), sete em cada dez casos de golpe, no pa\u00eds, n\u00e3o miram a seguran\u00e7a dos sistemas em si, mas sim o cliente final. Portanto, \u00e9 cada vez mais importante que as pessoas estejam atentas para identificarem rapidamente qualquer tentativa de golpe. E para alertar o p\u00fablico e auxiliar a identificar e evitar abordagens criminosas, o Banco do Brasil estreia uma nova campanha, a partir desta quarta-feira, 19. A comunica\u00e7\u00e3o assinada pela Lew\u2019Lara\\TBWA traz o conceito &#8220;Desconfiou que \u00e9 golpe? Procure o BB&#8221;, refor\u00e7ando o comprometimento com a confian\u00e7a e seguran\u00e7a banc\u00e1ria dos brasileiros.<\/p>\n<p><a href=\"https:\/\/www.cidademarketing.com.br\/marketing\/sua-marca-vai-virar-noticia\/\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-44329 aligncenter\" src=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2023\/04\/cidademarketing_backlinks_marketingdigital_publieditorial_.png\" alt=\"\" width=\"500\" height=\"500\" \/><\/a><\/p>\n<p>Rafael Giovanella, diretor de Controles Internos e que acumula o cargo de gerente geral da Unidade Cyber e Preven\u00e7\u00e3o a Fraudes do Banco do Brasil, explica que a maior parte dos crimes virtuais est\u00e1 vinculada \u00e0 engenharia social, manipula\u00e7\u00e3o psicol\u00f3gica da v\u00edtima para que ela forne\u00e7a informa\u00e7\u00f5es confidenciais como senhas, n\u00fameros de cart\u00f5es, ou fa\u00e7a transa\u00e7\u00f5es em favor dos criminosos. \u201cO golpista se vale da falta de conhecimento, descuido ou ingenuidade da pessoa que ele aborda. Por isso, o Banco do Brasil investe na dissemina\u00e7\u00e3o da cultura de seguran\u00e7a digital. Essa campanha mostra a relev\u00e2ncia da educa\u00e7\u00e3o na forma\u00e7\u00e3o de um cidad\u00e3o digital seguro e consciente\u201d, explica.<\/p>\n<p>Jailma Ribeiro e Guilherme Branco, diretores de cria\u00e7\u00e3o associados da Lew\u2019Lara\\TBWA, comentam que h\u00e1 previs\u00e3o de campanha mensal de alertas de seguran\u00e7a, trazendo dicas para que os clientes conhe\u00e7am e possam se proteger de cada tipo de golpe.<\/p>\n<p><iframe title=\"Spotify Embed: Podcast CidadeMarketing\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/show\/4khMKzP3FgFRWVwb73xicc?si=252fe5bff2b34909&#038;utm_source=oembed\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Queremos disseminar informa\u00e7\u00f5es confi\u00e1veis e escolhemos o sinal amarelo como personagem principal. \u00c9 um s\u00edmbolo de alerta que todo mundo conhece e que tem a cor do BB. A ideia \u00e9 refor\u00e7ar que o Banco do Brasil \u00e9 um aliado nesse processo de proteger os clientes&#8221;, completa Paula Say\u00e3o, diretora de marketing e comunica\u00e7\u00e3o do BB.<\/p>\n<div class=\"youtube-embed\" data-video_id=\"Bkf5FcHS_Dg\"><iframe title=\"Golpe da Falsa Central? Na d\u00favida, procure o BB.\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/Bkf5FcHS_Dg?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>FICHA T\u00c9CNICA<br \/>\nT\u00edtulo: CAMPANHA SEGURAN\u00c7A 2023 (CYBER SECURITY)<br \/>\nAg\u00eancia: LEW\u2019LARA\\TBWA<br \/>\nCliente: Banco do Brasil<br \/>\nCEO: Marcia Esteves<br \/>\nDire\u00e7\u00e3o Executiva de Cria\u00e7\u00e3o: Rodrigo Tortima e Rodrigo da Matta<br \/>\nDire\u00e7\u00e3o de Cria\u00e7\u00e3o Associada: Jailma Ribeiro e Guilherme Branco<br \/>\nDire\u00e7\u00e3o de Arte: Natalia Calvoso<br \/>\nReda\u00e7\u00e3o: Polyana Bandeira<br \/>\nManaging Director: Duda Guedes<br \/>\nNeg\u00f3cios: Daniela Rios, Tatiana Lucena e Jana\u00edna Bourguignon<br \/>\nCSO: Raquel Messias<br \/>\nEstrat\u00e9gia: Ma\u00edra Miguel<br \/>\nRela\u00e7\u00f5es P\u00fablicas: Amanda Brand\u00e3o e Yasmin Zampieri<br \/>\nCDMO: Vicente Varela<br \/>\nM\u00eddia: Luisa Sotero, Anderson Cabral, Barbara Sousa, J\u00e9ssica Louren\u00e7o e Camila Rodrigues<br \/>\nBI: Fernanda Gamarski e Felipe Pineda<br \/>\nCCOO:\u2002Elise Passamani<br \/>\nOpera\u00e7\u00f5es: Fran David<br \/>\nProjetos: Ana Gaud\u00eancio<br \/>\nProdu\u00e7\u00e3o de RTV:\u2002Izabel Soares, Elaine Vilar e Wilza Godoy<br \/>\nProdu\u00e7\u00e3o Gr\u00e1fica: Rodrigo Giammarino e Magali Iwata<br \/>\nProdutora de Filme: O2 Filmes<br \/>\nDire\u00e7\u00e3o de Cena: Fernando Moreira<br \/>\nProdu\u00e7\u00e3o Executiva: Fl\u00e1via Zanini | Amanda Rossi<br \/>\nProdu\u00e7\u00e3o: Fl\u00e1via Zanini | Amanda Rossi<br \/>\nMontagem:\u2002Miguel Thom\u00e9<br \/>\nCoordena\u00e7\u00e3o de P\u00f3s:\u2002O2 P\u00f3s<br \/>\nFinaliza\u00e7\u00e3o: Miguel Thom\u00e9<br \/>\nProdutora de Som: Sat\u00e9lite \u00c1udio<br \/>\nProdu\u00e7\u00e3o Executiva: Roberto Coelho, Kito Siqueira e Hurso Ambrifi<br \/>\nProdu\u00e7\u00e3o: Roberto Coelho, Hurso Ambrifi, Charly Coombes, Thiago Colli, Koitty e Pedro Motta<br \/>\nLocu\u00e7\u00e3o: Simone Kliass | Thiago Colli<br \/>\nTrilha: Roberto Coelho, Hurso Ambrifi, Charly Coombes, Thiago Colli, Koitty e Pedro Motta<br \/>\nAprova\u00e7\u00e3o Cliente: Paula Say\u00e3o, Ana Carolina Castro, Elvis Kleber Figueiredo, Igor Ara\u00fajo e Keyler Alves<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguran\u00e7a \u00e9 a palavra da vez. De acordo com a Federa\u00e7\u00e3o Brasileira de Bancos (Febraban), sete em cada dez casos de golpe, no pa\u00eds, n\u00e3o miram a seguran\u00e7a dos sistemas em si, mas sim o cliente final. Portanto, \u00e9 cada vez mais importante que as pessoas estejam atentas para identificarem rapidamente qualquer tentativa de golpe. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[14],"tags":[576,167,65,33,28,66,181],"class_list":["post-46235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos","tag-banco-do-brasil","tag-bb","tag-campanha","tag-estrategia","tag-marketing","tag-propaganda","tag-publicidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Banco do Brasil lan\u00e7a campanha inovadora focada em seguran\u00e7a e prote\u00e7\u00e3o financeira - CidadeMarketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banco do Brasil lan\u00e7a campanha inovadora focada em seguran\u00e7a e prote\u00e7\u00e3o financeira - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"Seguran\u00e7a \u00e9 a palavra da vez. De acordo com a Federa\u00e7\u00e3o Brasileira de Bancos (Febraban), sete em cada dez casos de golpe, no pa\u00eds, n\u00e3o miram a seguran\u00e7a dos sistemas em si, mas sim o cliente final. Portanto, \u00e9 cada vez mais importante que as pessoas estejam atentas para identificarem rapidamente qualquer tentativa de golpe. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-19T13:05:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2023\/07\/bbseguranca_01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1839\" \/>\n\t<meta property=\"og:image:height\" content=\"1005\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"Banco do Brasil lan\u00e7a campanha inovadora focada em seguran\u00e7a e prote\u00e7\u00e3o financeira\",\"datePublished\":\"2023-07-19T13:05:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/\"},\"wordCount\":632,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bbseguranca_01.png\",\"keywords\":[\"Banco do Brasil\",\"BB\",\"campanha\",\"estrat\u00e9gia\",\"marketing\",\"propaganda\",\"publicidade\"],\"articleSection\":[\"Videos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/\",\"name\":\"Banco do Brasil lan\u00e7a campanha inovadora focada em seguran\u00e7a e prote\u00e7\u00e3o financeira - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bbseguranca_01.png\",\"datePublished\":\"2023-07-19T13:05:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bbseguranca_01.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bbseguranca_01.png\",\"width\":1839,\"height\":1005,\"caption\":\"Reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2023\\\/07\\\/19\\\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banco do Brasil lan\u00e7a campanha inovadora focada em seguran\u00e7a e prote\u00e7\u00e3o financeira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Banco do Brasil lan\u00e7a campanha inovadora focada em seguran\u00e7a e prote\u00e7\u00e3o financeira - CidadeMarketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/","og_locale":"pt_BR","og_type":"article","og_title":"Banco do Brasil lan\u00e7a campanha inovadora focada em seguran\u00e7a e prote\u00e7\u00e3o financeira - CidadeMarketing","og_description":"Seguran\u00e7a \u00e9 a palavra da vez. De acordo com a Federa\u00e7\u00e3o Brasileira de Bancos (Febraban), sete em cada dez casos de golpe, no pa\u00eds, n\u00e3o miram a seguran\u00e7a dos sistemas em si, mas sim o cliente final. Portanto, \u00e9 cada vez mais importante que as pessoas estejam atentas para identificarem rapidamente qualquer tentativa de golpe. [&hellip;]","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2023-07-19T13:05:49+00:00","og_image":[{"width":1839,"height":1005,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2023\/07\/bbseguranca_01.png","type":"image\/png"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"Banco do Brasil lan\u00e7a campanha inovadora focada em seguran\u00e7a e prote\u00e7\u00e3o financeira","datePublished":"2023-07-19T13:05:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/"},"wordCount":632,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2023\/07\/bbseguranca_01.png","keywords":["Banco do Brasil","BB","campanha","estrat\u00e9gia","marketing","propaganda","publicidade"],"articleSection":["Videos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/","name":"Banco do Brasil lan\u00e7a campanha inovadora focada em seguran\u00e7a e prote\u00e7\u00e3o financeira - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2023\/07\/bbseguranca_01.png","datePublished":"2023-07-19T13:05:49+00:00","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2023\/07\/bbseguranca_01.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2023\/07\/bbseguranca_01.png","width":1839,"height":1005,"caption":"Reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2023\/07\/19\/banco-do-brasil-lanca-campanha-inovadora-focada-em-seguranca-e-protecao-financeira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"Banco do Brasil lan\u00e7a campanha inovadora focada em seguran\u00e7a e prote\u00e7\u00e3o financeira"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/46235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=46235"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/46235\/revisions"}],"predecessor-version":[{"id":46237,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/46235\/revisions\/46237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/46236"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=46235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=46235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=46235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}