{"id":4462,"date":"2018-12-26T23:34:09","date_gmt":"2018-12-27T01:34:09","guid":{"rendered":"http:\/\/www.cidademarketing.com.br\/marketing\/?p=4462"},"modified":"2018-12-26T23:34:12","modified_gmt":"2018-12-27T01:34:12","slug":"banco-central-apresenta-novo-site","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/","title":{"rendered":"Banco Central apresenta novo site"},"content":{"rendered":"\n<p>O site do Banco Central (BC) passou por reformula\u00e7\u00e3o completa ao longo dos dois \u00faltimos anos. A mudan\u00e7a moderniza o portal do ponto de vista tecnol\u00f3gico e revisa conte\u00fado, linguagem, estrutura de navega\u00e7\u00e3o, acessibilidade e usabilidade. Reformulada, a nova p\u00e1gina na Internet tem leiaute moderno, navega\u00e7\u00e3o simplificada, gr\u00e1ficos din\u00e2micos e imagens did\u00e1ticas. A a\u00e7\u00e3o faz parte da Agenda BC+, no pilar Mais Cidadania Financeira.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"hD32ZS4_ZEQ\"><iframe title=\"Novo site do BC\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/hD32ZS4_ZEQ?feature=oembed&#038;enablejsapi=1&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>\u201cO site atual recebe milh\u00f5es de visitas a cada ano e cont\u00e9m informa\u00e7\u00f5es muito \u00fateis. Nosso desafio foi transformar esse reposit\u00f3rio de informa\u00e7\u00f5es em um instrumento ainda melhor de comunica\u00e7\u00e3o e de relacionamento com a sociedade\u201d, afirma Eduardo Daniel de Souza, chefe do Departamento de Comunica\u00e7\u00e3o do BC.<\/p>\n\n\n\n<p>Uma das principais novidades \u00e9 a estrutura de navega\u00e7\u00e3o tem\u00e1tica focada nos dois aspectos da miss\u00e3o institucional: pol\u00edtica monet\u00e1ria e estabilidade financeira. \u201cFizemos ampla pesquisa sobre tend\u00eancias de comunica\u00e7\u00e3o digital e realizamos benchmarking com sites de outras institui\u00e7\u00f5es e bancos centrais para criarmos uma p\u00e1gina com foco no usu\u00e1rio, linguagem acess\u00edvel e capaz de conectar melhor o BC com o cidad\u00e3o e, ao mesmo tempo, aprimorar os conte\u00fados de qualidade para especialistas, analistas de mercado e pesquisadores\u201d, explica Eduardo Daniel.<\/p>\n\n\n\n<p>A usabilidade foi outro aspecto importante do projeto. Sob o conceito de megamenu, funcionalidade que expande o menu principal e permite utiliz\u00e1-lo para exibir diversos tipos de informa\u00e7\u00e3o, a navega\u00e7\u00e3o alcan\u00e7a todo o site, em seus v\u00e1rios n\u00edveis, a partir de qualquer ponto da p\u00e1gina, sem necessidade de retornar \u00e0 p\u00e1gina inicial. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O site do Banco Central (BC) passou por reformula\u00e7\u00e3o completa ao longo dos dois \u00faltimos anos. A mudan\u00e7a moderniza o portal do ponto de vista tecnol\u00f3gico e revisa conte\u00fado, linguagem, estrutura de navega\u00e7\u00e3o, acessibilidade e usabilidade. Reformulada, a nova p\u00e1gina na Internet tem leiaute moderno, navega\u00e7\u00e3o simplificada, gr\u00e1ficos din\u00e2micos e imagens did\u00e1ticas. A a\u00e7\u00e3o faz [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[11,6],"tags":[139,255,136,993,904],"class_list":["post-4462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digital","category-noticias","tag-banco-central","tag-bc","tag-internet","tag-site","tag-web"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Banco Central apresenta novo site - CidadeMarketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banco Central apresenta novo site - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"O site do Banco Central (BC) passou por reformula\u00e7\u00e3o completa ao longo dos dois \u00faltimos anos. A mudan\u00e7a moderniza o portal do ponto de vista tecnol\u00f3gico e revisa conte\u00fado, linguagem, estrutura de navega\u00e7\u00e3o, acessibilidade e usabilidade. Reformulada, a nova p\u00e1gina na Internet tem leiaute moderno, navega\u00e7\u00e3o simplificada, gr\u00e1ficos din\u00e2micos e imagens did\u00e1ticas. A a\u00e7\u00e3o faz [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-27T01:34:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-27T01:34:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2018\/12\/bancocentral_site.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"845\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"Banco Central apresenta novo site\",\"datePublished\":\"2018-12-27T01:34:09+00:00\",\"dateModified\":\"2018-12-27T01:34:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/\"},\"wordCount\":299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/bancocentral_site.jpg\",\"keywords\":[\"Banco Central\",\"BC\",\"internet\",\"site\",\"web\"],\"articleSection\":[\"Digital\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/\",\"name\":\"Banco Central apresenta novo site - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/bancocentral_site.jpg\",\"datePublished\":\"2018-12-27T01:34:09+00:00\",\"dateModified\":\"2018-12-27T01:34:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/bancocentral_site.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/bancocentral_site.jpg\",\"width\":1920,\"height\":845,\"caption\":\"Reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2018\\\/12\\\/26\\\/banco-central-apresenta-novo-site\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banco Central apresenta novo site\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Banco Central apresenta novo site - CidadeMarketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/","og_locale":"pt_BR","og_type":"article","og_title":"Banco Central apresenta novo site - CidadeMarketing","og_description":"O site do Banco Central (BC) passou por reformula\u00e7\u00e3o completa ao longo dos dois \u00faltimos anos. A mudan\u00e7a moderniza o portal do ponto de vista tecnol\u00f3gico e revisa conte\u00fado, linguagem, estrutura de navega\u00e7\u00e3o, acessibilidade e usabilidade. Reformulada, a nova p\u00e1gina na Internet tem leiaute moderno, navega\u00e7\u00e3o simplificada, gr\u00e1ficos din\u00e2micos e imagens did\u00e1ticas. A a\u00e7\u00e3o faz [&hellip;]","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2018-12-27T01:34:09+00:00","article_modified_time":"2018-12-27T01:34:12+00:00","og_image":[{"width":1920,"height":845,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2018\/12\/bancocentral_site.jpg","type":"image\/jpeg"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"Banco Central apresenta novo site","datePublished":"2018-12-27T01:34:09+00:00","dateModified":"2018-12-27T01:34:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/"},"wordCount":299,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2018\/12\/bancocentral_site.jpg","keywords":["Banco Central","BC","internet","site","web"],"articleSection":["Digital","Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/","name":"Banco Central apresenta novo site - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2018\/12\/bancocentral_site.jpg","datePublished":"2018-12-27T01:34:09+00:00","dateModified":"2018-12-27T01:34:12+00:00","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2018\/12\/bancocentral_site.jpg","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2018\/12\/bancocentral_site.jpg","width":1920,"height":845,"caption":"Reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2018\/12\/26\/banco-central-apresenta-novo-site\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"Banco Central apresenta novo site"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/4462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=4462"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/4462\/revisions"}],"predecessor-version":[{"id":4464,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/4462\/revisions\/4464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/4463"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=4462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=4462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=4462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}