{"id":30828,"date":"2021-10-24T23:20:10","date_gmt":"2021-10-25T02:20:10","guid":{"rendered":"https:\/\/www.cidademarketing.com.br\/marketing\/?p=30828"},"modified":"2021-10-24T23:20:12","modified_gmt":"2021-10-25T02:20:12","slug":"nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/","title":{"rendered":"NBA celebra sucesso de parceria com Budweiser e prepara novidades para a temporada 2021-2022"},"content":{"rendered":"\n<p><\/p><iframe src=\"https:\/\/open.spotify.com\/embed\/show\/4khMKzP3FgFRWVwb73xicc\" width=\"100%\" height=\"232\" frameBorder=\"0\" allowtransparency=\"true\" allow=\"encrypted-media\"><\/iframe>\t\n\n\n\n\n<p>Uma quebra de paradigmas. O mercado foi surpreendido no in\u00edcio de 2021 por um acordo in\u00e9dito entre NBA e Budweiser que tornou a marca emissora oficial da liga no pa\u00eds. Um novo conceito de parceira, pioneiro no mundo, que avan\u00e7a para a segunda temporada, e j\u00e1 est\u00e1 marcado pelos n\u00fameros impressionantes alcan\u00e7ados no ambiente digital, pelas a\u00e7\u00f5es de engajamento com f\u00e3s, promovendo campanhas, intera\u00e7\u00f5es e experi\u00eancias, al\u00e9m do reconhecimento em premia\u00e7\u00f5es internacionais conquistadas ao longo do ano. Com o in\u00edcio da temporada 2021-2022 &#8211; marco de 75 anos da liga -, a certeza \u00e9 de que muitas novidades est\u00e3o por vir.<\/p>\n\n\n\n<p>&#8211; Estamos construindo uma nova hist\u00f3ria, apresentando um modelo que combina inova\u00e7\u00e3o, ousadia e conte\u00fado, pensado e desenvolvido para uma incr\u00edvel experi\u00eancia para os nossos f\u00e3s. Sa\u00edmos do tradicional, criamos oportunidades, possibilidades em diversas m\u00eddias, um conceito especial e \u00fanico de parceria, e \u00e9 s\u00f3 o come\u00e7o afirmou Rodrigo Vicentini, Head da NBA no Brasil.<\/p>\n\n\n\n<p>Al\u00e9m do lockup exclusivo expondo marca e liga lado a lado em todos os momentos, identidade que refor\u00e7a o status de &#8216;Emissora Oficial da NBA&#8217; de Budweiser, foram desenvolvidos pacotes gr\u00e1ficos contendo abertura, trilhas e vinhetas especialmente para os jogos NBA Bud. Todas as transmiss\u00f5es de TV e nos canais do YouTube contaram ainda com conte\u00fados especiais produzidos em conjunto, incluindo entrevistas in\u00e9ditas, materiais de bastidores, curiosidades e um pouco do lado lifestyle da liga.<\/p>\n\n\n\n<p>&#8211; Foram mais de 500h de conte\u00fados in\u00e9ditos, entre jogos transmitidos ao vivo e materiais produzidos pelo nosso time de conte\u00fado junto com Bud. E o reconhecimento, as premia\u00e7\u00f5es que recebemos, nos enchem de orgulho. Temos uma nova temporada come\u00e7ando, especial pelo anivers\u00e1rio de 75 anos, e que vai levar ainda mais emo\u00e7\u00e3o para os f\u00e3s. Vem muita coisa boa por a\u00ed, vamos surpreender ainda mais &#8211; completou.<\/p>\n\n\n\n<p>A primeira rodada dupla NBA Bud da nova temporada ser\u00e1 na noite desta quinta-feira, dia 21, abrindo uma s\u00e9rie de mais de 100 partidas que ser\u00e3o exibidas ao vivo em canais\/plataformas tais como TV Bandeirantes (TV aberta), SporTV (TV fechada), canal do Gaules (Twitch) e TNT Sports (YouTube).<\/p>\n\n\n\n<p>PREMIA\u00c7\u00d5ES INTERNACIONAIS<br>\u2022 2021 International Business Awards (IBA Stevie Awards) &#8211; Gold<br>\u00b7 &#8216;Melhor Campanha de Marketing do Ano \/ M\u00eddia e Entretenimento&#8217;<br>\u2022 Pr\u00eamio NBA de Inova\u00e7\u00e3o 2021<br>\u2022 Titan Business Awards 2021 &#8211; Platinum<br>\u00b7 &#8216;Melhor Iniciativa de Marketing em Esportes&#8217;<br>\u2022 Titan Business Awards 2021 &#8211; Gold<br>\u00b7 &#8216;Melhor Campanha de Marketing de Marca&#8217;<br>\u2022 Sports Pro OTT Awards 2021 &#8211; Finalista \/ categoria &#8216;Inova\u00e7\u00e3o do Ano&#8217;<br>\u00b7 (vencedores ser\u00e3o anunciados em 15 de novembro)<br>\u2022 SABRE Awards Latin America 2021<br>\u00b7 Finalista Top 5 cases &#8211; Brasil<\/p>\n\n\n\n<p>N\u00daMEROS DA PARCERIA \/ TEMPORADA 2020-2021<br>\u2022 Ao todo, foram 106 transmiss\u00f5es de jogos NBA Bud (66 no SporTV, 58 na TV Bandeirantes, 98 no canal da NBA Brasil no YouTube, seis no canal da TNT Sports no YouTube e 15 na Twitch \/ canal do Gaules)<br>\u00b7 Canal do Gaules (Twitch): 3,5 milh\u00f5es de horas assistidas, 73,3 mil (m\u00e9dia de aparelhos conectados), 156,2 mil (pico de aparelhos conectados), 4 milh\u00f5es de videoviews e quase 50h de transmiss\u00f5es<br>\u00b7 YouTube (apenas jogos ao vivo): 4,2 milh\u00f5es de engajamento totais (curtidas + coment\u00e1rios + compartilhamentos), 423 mi de impress\u00f5es (total), 31,7 mi videoviews (total), 10,5 mi de horas assistidas e pico de 117 mil usu\u00e1rios simult\u00e2neos<br>\u2022 Mais de 500h de conte\u00fado in\u00e9dito NBA Bud produzido ao longo da temporada (al\u00e9m dos jogos) com um &#8216;card\u00e1pio variado&#8217; que incluiu s\u00e9ries exclusivas e programas como &#8216;Resenha Bud&#8217;, &#8216;Rodada NBA&#8217;, &#8216;Spoiler Bud&#8217;, &#8216;Viralizou&#8217;, &#8216;Bud Cam&#8217;, &#8216;Batalhas de Rap Bud-NBA&#8217;, &#8216;Rap com Brazza&#8217;, &#8216;Melhores Momentos Bud&#8217;, &#8216;Kings da Semana&#8217; e &#8216;Os Criadores&#8217;<br>\u2022 Cobertura in loco com rep\u00f3rter Bud nas arenas durante as Finals da Confer\u00eancia Leste<br>\u2022 Transmiss\u00f5es exclusivas com participa\u00e7\u00e3o de influencers para o canal Budweiser BR<br>\u2022 Jogos Cl\u00e1ssicos durante o per\u00edodo de offseason<br>\u2022 Entre fevereiro e julho (fim da temporada 2020-2021), foram quase 2,7 mil posts em redes sociais da NBA Brasil divulgando jogos e os programas NBA Bud. Juntos, eles alcan\u00e7aram 11,5 milh\u00f5es de impress\u00f5es, 6,3 mi intera\u00e7\u00f5es e 20,2 mi visualiza\u00e7\u00f5es.<br>\u2022 As comunica\u00e7\u00f5es de email promovendo os jogos NBA Bud transmitidos combinaram para 4,8 milh\u00f5es de impactos A\u00c7\u00d5ES DE PATROC\u00cdNIO<br>\u2022 Desafio &#8216;Cestou com Kings&#8217;<br>\u2022 Campanhas &#8216;Placas&#8217; e &#8216;Ningu\u00e9m Sonha Sozinho&#8217;<br>\u2022 Bud Challenges<br>\u2022 Hospitalidade: envio de kits &#8216;NBA na sua casa&#8217; e presen\u00e7a de influencers nas Finals<br>\u2022 NBA House Digital 2021, apresentada por Budweiser<br>\u00b7 Entrevista exclusiva com Giannis Antetokounmpo<br>\u00b7 Meet &amp; Greets com &#8216;Lendas&#8217; da NBA<br>\u00b7 e-mail Marketing<br>\u00b7 Bares e \u00c1rea Vip Budweiser<br>\u00b7 Treasure Hunt Bud<br>\u00b7 Leaderboard e avatares exclusivos customizados<br>\u00b7 Exposi\u00e7\u00e3o de marca na plataforma, em redes sociais NBA e comunica\u00e7\u00e3o do evento<\/p>\n\n\n\n<p><\/p><iframe allow=\"autoplay *; encrypted-media *; fullscreen *\" frameborder=\"0\" height=\"450\" style=\"width:100%;max-width:660px;overflow:hidden;background:transparent;\" sandbox=\"allow-forms allow-popups allow-same-origin allow-scripts allow-storage-access-by-user-activation allow-top-navigation-by-user-activation\" src=\"https:\/\/embed.podcasts.apple.com\/br\/podcast\/podcast-cidademarketing\/id1371923283\"><\/iframe>\n\n","protected":false},"excerpt":{"rendered":"<p>Uma quebra de paradigmas. O mercado foi surpreendido no in\u00edcio de 2021 por um acordo in\u00e9dito entre NBA e Budweiser que tornou a marca emissora oficial da liga no pa\u00eds. Um novo conceito de parceira, pioneiro no mundo, que avan\u00e7a para a segunda temporada, e j\u00e1 est\u00e1 marcado pelos n\u00fameros impressionantes alcan\u00e7ados no ambiente digital, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6],"tags":[1673,33,28,2866,235],"class_list":["post-30828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-budweiser","tag-estrategia","tag-marketing","tag-nba","tag-parceria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NBA celebra sucesso de parceria com Budweiser e prepara novidades para a temporada 2021-2022 - CidadeMarketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NBA celebra sucesso de parceria com Budweiser e prepara novidades para a temporada 2021-2022 - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"Uma quebra de paradigmas. O mercado foi surpreendido no in\u00edcio de 2021 por um acordo in\u00e9dito entre NBA e Budweiser que tornou a marca emissora oficial da liga no pa\u00eds. Um novo conceito de parceira, pioneiro no mundo, que avan\u00e7a para a segunda temporada, e j\u00e1 est\u00e1 marcado pelos n\u00fameros impressionantes alcan\u00e7ados no ambiente digital, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-25T02:20:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-25T02:20:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/398950_990287_bud_nba_lockup_pt.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1785\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"NBA celebra sucesso de parceria com Budweiser e prepara novidades para a temporada 2021-2022\",\"datePublished\":\"2021-10-25T02:20:10+00:00\",\"dateModified\":\"2021-10-25T02:20:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/\"},\"wordCount\":809,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/398950_990287_bud_nba_lockup_pt.png\",\"keywords\":[\"Budweiser\",\"estrat\u00e9gia\",\"marketing\",\"NBA\",\"parceria\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/\",\"name\":\"NBA celebra sucesso de parceria com Budweiser e prepara novidades para a temporada 2021-2022 - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/398950_990287_bud_nba_lockup_pt.png\",\"datePublished\":\"2021-10-25T02:20:10+00:00\",\"dateModified\":\"2021-10-25T02:20:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/398950_990287_bud_nba_lockup_pt.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/398950_990287_bud_nba_lockup_pt.png\",\"width\":1785,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/24\\\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NBA celebra sucesso de parceria com Budweiser e prepara novidades para a temporada 2021-2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NBA celebra sucesso de parceria com Budweiser e prepara novidades para a temporada 2021-2022 - CidadeMarketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/","og_locale":"pt_BR","og_type":"article","og_title":"NBA celebra sucesso de parceria com Budweiser e prepara novidades para a temporada 2021-2022 - CidadeMarketing","og_description":"Uma quebra de paradigmas. O mercado foi surpreendido no in\u00edcio de 2021 por um acordo in\u00e9dito entre NBA e Budweiser que tornou a marca emissora oficial da liga no pa\u00eds. Um novo conceito de parceira, pioneiro no mundo, que avan\u00e7a para a segunda temporada, e j\u00e1 est\u00e1 marcado pelos n\u00fameros impressionantes alcan\u00e7ados no ambiente digital, [&hellip;]","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2021-10-25T02:20:10+00:00","article_modified_time":"2021-10-25T02:20:12+00:00","og_image":[{"width":1785,"height":1080,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/398950_990287_bud_nba_lockup_pt.png","type":"image\/png"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"NBA celebra sucesso de parceria com Budweiser e prepara novidades para a temporada 2021-2022","datePublished":"2021-10-25T02:20:10+00:00","dateModified":"2021-10-25T02:20:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/"},"wordCount":809,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/398950_990287_bud_nba_lockup_pt.png","keywords":["Budweiser","estrat\u00e9gia","marketing","NBA","parceria"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/","name":"NBA celebra sucesso de parceria com Budweiser e prepara novidades para a temporada 2021-2022 - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/398950_990287_bud_nba_lockup_pt.png","datePublished":"2021-10-25T02:20:10+00:00","dateModified":"2021-10-25T02:20:12+00:00","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/398950_990287_bud_nba_lockup_pt.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/398950_990287_bud_nba_lockup_pt.png","width":1785,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/24\/nba-celebra-sucesso-de-parceria-com-budweiser-e-prepara-novidades-para-a-temporada-2021-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"NBA celebra sucesso de parceria com Budweiser e prepara novidades para a temporada 2021-2022"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/30828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=30828"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/30828\/revisions"}],"predecessor-version":[{"id":30830,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/30828\/revisions\/30830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/30829"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=30828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=30828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=30828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}