{"id":30168,"date":"2021-10-06T12:51:39","date_gmt":"2021-10-06T15:51:39","guid":{"rendered":"https:\/\/www.cidademarketing.com.br\/marketing\/?p=30168"},"modified":"2021-10-06T12:51:42","modified_gmt":"2021-10-06T15:51:42","slug":"no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/","title":{"rendered":"No Dia das Crian\u00e7as, Canal Futura ganha grade especial para p\u00fablico infantil com estreia do Quintal TV e da Caverna de Petra"},"content":{"rendered":"\n<p><\/p><iframe src=\"https:\/\/open.spotify.com\/embed\/show\/4khMKzP3FgFRWVwb73xicc\" width=\"100%\" height=\"232\" frameBorder=\"0\" allowtransparency=\"true\" allow=\"encrypted-media\"><\/iframe>\t\n\n\n\n\n<p>O Dia das Crian\u00e7as ganha uma programa\u00e7\u00e3o in\u00e9dita no Canal Futura com a estreia da Caverna de Petra e do Quintal TV. As duas programa\u00e7\u00f5es fazem parte de uma nova grade do canal, focada no p\u00fablico infantil, e s\u00e3o as primeiras produ\u00e7\u00f5es originais para esta faixa et\u00e1ria. A Caverna de Petra \u00e9 uma s\u00e9rie com 13 epis\u00f3dios, de aproximadamente 15 minutos cada, que se passa dentro da \u201cCaverna das Lembran\u00e7as Esquecidas\u201d, um lugar m\u00e1gico e cheio de mem\u00f3rias importantes das crian\u00e7as que cresceram. Petra, a protagonista, mora sozinha na caverna e seu sonho \u00e9 conhecer uma crian\u00e7a humana como aquelas que deixaram por l\u00e1 brinquedos, desenhos e outras lembran\u00e7as. A s\u00e9rie tem pr\u00e9-estreia agendada para o dia 12 de outubro, \u00e0s 17h30 no Canal Futura, e estreia regular no dia 13 de outubro, \u00e0s 8h, com novos epis\u00f3dios todas as quartas-feiras. J\u00e1 o Quintal TV \u00e9 um programa que se passa num quintal, com crian\u00e7as brincando de fazer um programa de TV que \u00e9 apresentado por tr\u00eas influenciadores mirins: Davi Lucca Amorim, Rafael Chambarelli e Gabi Motta. A proposta \u00e9 desenvolver di\u00e1logos entre crian\u00e7as, cuidadores e especialistas acerca de assuntos contempor\u00e2neos com uma linguagem l\u00fadica, divertida e leve. Com 13 epis\u00f3dios, cada um com 13 minutos, a s\u00e9rie tem pr\u00e9-estreia agendada tamb\u00e9m para o dia 12, \u00e0s 17h45, e novos epis\u00f3dios toda quarta-feira, \u00e0s 8h15.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-2_@BRUNORYFER_0843-683x1024.jpg\" alt=\"\" data-id=\"30174\" data-full-url=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-2_@BRUNORYFER_0843-scaled.jpg\" data-link=\"https:\/\/www.cidademarketing.com.br\/marketing\/?attachment_id=30174\" class=\"wp-image-30174\" srcset=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-2_@BRUNORYFER_0843-683x1024.jpg 683w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-2_@BRUNORYFER_0843-200x300.jpg 200w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-2_@BRUNORYFER_0843-768x1152.jpg 768w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-2_@BRUNORYFER_0843-1024x1536.jpg 1024w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-2_@BRUNORYFER_0843-1365x2048.jpg 1365w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-2_@BRUNORYFER_0843-280x420.jpg 280w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-2_@BRUNORYFER_0843-640x960.jpg 640w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-2_@BRUNORYFER_0843-681x1022.jpg 681w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-2_@BRUNORYFER_0843-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_3-1024x683.jpg\" alt=\"\" data-id=\"30171\" data-full-url=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_3-scaled.jpg\" data-link=\"https:\/\/www.cidademarketing.com.br\/marketing\/?attachment_id=30171\" class=\"wp-image-30171\" srcset=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_3-1024x683.jpg 1024w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_3-300x200.jpg 300w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_3-768x512.jpg 768w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_3-1536x1024.jpg 1536w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_3-2048x1365.jpg 2048w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_3-630x420.jpg 630w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_3-640x427.jpg 640w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_3-681x454.jpg 681w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_2-683x1024.jpg\" alt=\"\" data-id=\"30170\" data-full-url=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_2-scaled.jpg\" data-link=\"https:\/\/www.cidademarketing.com.br\/marketing\/?attachment_id=30170\" class=\"wp-image-30170\" srcset=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_2-683x1024.jpg 683w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_2-200x300.jpg 200w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_2-768x1152.jpg 768w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_2-1024x1536.jpg 1024w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_2-1365x2048.jpg 1365w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_2-280x420.jpg 280w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_2-640x960.jpg 640w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_2-681x1022.jpg 681w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_2-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_1-1024x683.jpg\" alt=\"\" data-id=\"30169\" data-full-url=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_1-scaled.jpg\" data-link=\"https:\/\/www.cidademarketing.com.br\/marketing\/?attachment_id=30169\" class=\"wp-image-30169\" srcset=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_1-1024x683.jpg 1024w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_1-300x200.jpg 300w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_1-768x512.jpg 768w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_1-1536x1024.jpg 1536w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_1-2048x1365.jpg 2048w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_1-630x420.jpg 630w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_1-640x427.jpg 640w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/CavernaDePetra_1-681x454.jpg 681w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Na Caverna de Petra s\u00e3o abordados sentimentos como medo, autoestima, competitividade, ansiedade e autoconhecimento, sempre mostrando como \u00e9 poss\u00edvel superar as coisas ruins e continuar sendo feliz. Alguns temas sociais tamb\u00e9m fazem parte do seriado, como o cuidado com o meio ambiente, padr\u00f5es impostos \u00e0s mulheres, igualdade de g\u00eanero, ass\u00e9dio e desinforma\u00e7\u00e3o, abordados sempre de forma educativa e l\u00fadica para que as crian\u00e7as comecem a entender como podem enfrentar essas quest\u00f5es. Na maioria das vezes, a resolu\u00e7\u00e3o de um problema surge a partir de uma conversa com o Seu Profundeza, uma alus\u00e3o \u00e0 import\u00e2ncia do autoconhecimento e da rela\u00e7\u00e3o de saber ouvir a si mesmo. Dirigida por Tom Gitahy, e Rica Saito, a s\u00e9rie \u00e9 dedicada \u00e0 faixa et\u00e1ria de 7 a 10 anos.<\/p>\n\n\n\n<p>J\u00e1 o Quintal TV \u00e9 uma produ\u00e7\u00e3o da Delicatessen, com consultoria de Waldete Trist\u00e3o e dire\u00e7\u00e3o de Pablo Uranga. No cen\u00e1rio, os protagonistas Davi e Rafa apresentam o programa atr\u00e1s de uma bancada e usam como ferramenta de trabalho um telefone de lata que conecta v\u00e1rios quintais do Brasil, possibilitando as entrevistas com os rep\u00f3rteres mirins. Enquanto isso, Gabi utiliza um computador de papel\u00e3o para entrar em contato com os especialistas, al\u00e9m de apresentar um quadro num balan\u00e7o fazendo entrevistas presenciais. Entre os principais temas est\u00e3o: ado\u00e7\u00e3o, g\u00eanero, negritude, educa\u00e7\u00e3o infantil, inclus\u00e3o e sustentabilidade.<\/p>\n\n\n\n<p>Os dois programas chegam com o intuito de fortalecer a rede de atua\u00e7\u00e3o do Futura dedicada \u00e0 Educa\u00e7\u00e3o B\u00e1sica, a fim de ampliar a representatividade das diferentes inf\u00e2ncias e adolesc\u00eancias nas telas e o alcance de atua\u00e7\u00e3o nos territ\u00f3rios brasileiros. A ideia \u00e9 entregar uma faixa infantil que aborda diversidade, identidade e direito das crian\u00e7as. At\u00e9 o fim do ano, o Canal promove um conjunto de iniciativas multiplataformas com conte\u00fados audiovisuais, cursos, mobiliza\u00e7\u00f5es que apoiam professores, estudantes e fam\u00edlias. Al\u00e9m das exibi\u00e7\u00f5es no Canal Futura, os epis\u00f3dios ficam dispon\u00edveis tamb\u00e9m nos Canais Globo e Globoplay.<\/p>\n\n\n\n<p><strong>SERVI\u00c7O:<\/strong><\/p>\n\n\n\n<p><strong><u>Caverna de Petra<\/u><\/strong><\/p>\n\n\n\n<p>Seriado com 13 epis\u00f3dios que aborda quest\u00f5es sociais e sentimentais na inf\u00e2ncia de forma l\u00fadica e leve.<\/p>\n\n\n\n<p><strong>Pr\u00e9-estreia<\/strong>: 12 de outubro, \u00e0s 17h30<\/p>\n\n\n\n<p><strong>Estreia: <\/strong>13 de outubro, com novos epis\u00f3dios toda quarta-feira, \u00e0s 8h.<\/p>\n\n\n\n<p><strong>Reprises:<\/strong> segunda e sexta, \u00e0s 8h. E segunda, quarta e sexta, \u00e0s 17h30<\/p>\n\n\n\n<p><strong>Classifica\u00e7\u00e3o:<\/strong> livre<\/p>\n\n\n\n<p><strong><u>Quintal TV<\/u><\/strong><\/p>\n\n\n\n<p>Programa apresentado por crian\u00e7as para o p\u00fablico infantil, com temas diversos sobre as pautas atuais, com linguagem l\u00fadica e convidados especiais.<\/p>\n\n\n\n<p><strong>Pr\u00e9-estreia:<\/strong> 12 de outubro, \u00e0s 17h45<\/p>\n\n\n\n<p><strong>Estreia:<\/strong> 13 de outubro, com novos epis\u00f3dios toda quarta-feira, \u00e0s 8h15<\/p>\n\n\n\n<p><strong>Reprises:<\/strong> segunda e sexta, \u00e0s 8h15. E segunda, quarta e sexta \u00e0s 17h45<\/p>\n\n\n\n<p><strong>Classifica\u00e7\u00e3o:<\/strong> Livre<\/p>\n\n\n\n<p><\/p><iframe allow=\"autoplay *; encrypted-media *; fullscreen *\" frameborder=\"0\" height=\"450\" style=\"width:100%;max-width:660px;overflow:hidden;background:transparent;\" sandbox=\"allow-forms allow-popups allow-same-origin allow-scripts allow-storage-access-by-user-activation allow-top-navigation-by-user-activation\" src=\"https:\/\/embed.podcasts.apple.com\/br\/podcast\/podcast-cidademarketing\/id1371923283\"><\/iframe>\n\n","protected":false},"excerpt":{"rendered":"<p>O Dia das Crian\u00e7as ganha uma programa\u00e7\u00e3o in\u00e9dita no Canal Futura com a estreia da Caverna de Petra e do Quintal TV. As duas programa\u00e7\u00f5es fazem parte de uma nova grade do canal, focada no p\u00fablico infantil, e s\u00e3o as primeiras produ\u00e7\u00f5es originais para esta faixa et\u00e1ria. A Caverna de Petra \u00e9 uma s\u00e9rie com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6],"tags":[3152,560,33,28,228],"class_list":["post-30168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-canal-futura","tag-dia-das-criancas","tag-estrategia","tag-marketing","tag-segmentacao-de-mercado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No Dia das Crian\u00e7as, Canal Futura ganha grade especial para p\u00fablico infantil com estreia do Quintal TV e da Caverna de Petra - CidadeMarketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No Dia das Crian\u00e7as, Canal Futura ganha grade especial para p\u00fablico infantil com estreia do Quintal TV e da Caverna de Petra - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"O Dia das Crian\u00e7as ganha uma programa\u00e7\u00e3o in\u00e9dita no Canal Futura com a estreia da Caverna de Petra e do Quintal TV. As duas programa\u00e7\u00f5es fazem parte de uma nova grade do canal, focada no p\u00fablico infantil, e s\u00e3o as primeiras produ\u00e7\u00f5es originais para esta faixa et\u00e1ria. A Caverna de Petra \u00e9 uma s\u00e9rie com [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-06T15:51:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-06T15:51:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-1_@BRUNORYFER-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"No Dia das Crian\u00e7as, Canal Futura ganha grade especial para p\u00fablico infantil com estreia do Quintal TV e da Caverna de Petra\",\"datePublished\":\"2021-10-06T15:51:39+00:00\",\"dateModified\":\"2021-10-06T15:51:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/\"},\"wordCount\":735,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/QUINTAL-TV-1_@BRUNORYFER-scaled.jpg\",\"keywords\":[\"Canal Futura\",\"Dia das Crian\u00e7as\",\"estrat\u00e9gia\",\"marketing\",\"segmenta\u00e7\u00e3o de mercado\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/\",\"name\":\"No Dia das Crian\u00e7as, Canal Futura ganha grade especial para p\u00fablico infantil com estreia do Quintal TV e da Caverna de Petra - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/QUINTAL-TV-1_@BRUNORYFER-scaled.jpg\",\"datePublished\":\"2021-10-06T15:51:39+00:00\",\"dateModified\":\"2021-10-06T15:51:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/QUINTAL-TV-1_@BRUNORYFER-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/QUINTAL-TV-1_@BRUNORYFER-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/10\\\/06\\\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No Dia das Crian\u00e7as, Canal Futura ganha grade especial para p\u00fablico infantil com estreia do Quintal TV e da Caverna de Petra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No Dia das Crian\u00e7as, Canal Futura ganha grade especial para p\u00fablico infantil com estreia do Quintal TV e da Caverna de Petra - CidadeMarketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/","og_locale":"pt_BR","og_type":"article","og_title":"No Dia das Crian\u00e7as, Canal Futura ganha grade especial para p\u00fablico infantil com estreia do Quintal TV e da Caverna de Petra - CidadeMarketing","og_description":"O Dia das Crian\u00e7as ganha uma programa\u00e7\u00e3o in\u00e9dita no Canal Futura com a estreia da Caverna de Petra e do Quintal TV. As duas programa\u00e7\u00f5es fazem parte de uma nova grade do canal, focada no p\u00fablico infantil, e s\u00e3o as primeiras produ\u00e7\u00f5es originais para esta faixa et\u00e1ria. A Caverna de Petra \u00e9 uma s\u00e9rie com [&hellip;]","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2021-10-06T15:51:39+00:00","article_modified_time":"2021-10-06T15:51:42+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-1_@BRUNORYFER-scaled.jpg","type":"image\/jpeg"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"No Dia das Crian\u00e7as, Canal Futura ganha grade especial para p\u00fablico infantil com estreia do Quintal TV e da Caverna de Petra","datePublished":"2021-10-06T15:51:39+00:00","dateModified":"2021-10-06T15:51:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/"},"wordCount":735,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-1_@BRUNORYFER-scaled.jpg","keywords":["Canal Futura","Dia das Crian\u00e7as","estrat\u00e9gia","marketing","segmenta\u00e7\u00e3o de mercado"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/","name":"No Dia das Crian\u00e7as, Canal Futura ganha grade especial para p\u00fablico infantil com estreia do Quintal TV e da Caverna de Petra - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-1_@BRUNORYFER-scaled.jpg","datePublished":"2021-10-06T15:51:39+00:00","dateModified":"2021-10-06T15:51:42+00:00","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-1_@BRUNORYFER-scaled.jpg","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/10\/QUINTAL-TV-1_@BRUNORYFER-scaled.jpg","width":2560,"height":1707,"caption":"Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/10\/06\/no-dia-das-criancas-canal-futura-ganha-grade-especial-para-publico-infantil-com-estreia-do-quintal-tv-e-da-caverna-de-petra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"No Dia das Crian\u00e7as, Canal Futura ganha grade especial para p\u00fablico infantil com estreia do Quintal TV e da Caverna de Petra"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/30168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=30168"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/30168\/revisions"}],"predecessor-version":[{"id":30175,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/30168\/revisions\/30175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/30173"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=30168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=30168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=30168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}