{"id":25983,"date":"2021-07-24T21:18:17","date_gmt":"2021-07-25T00:18:17","guid":{"rendered":"https:\/\/www.cidademarketing.com.br\/marketing\/?p=25983"},"modified":"2021-07-24T21:18:20","modified_gmt":"2021-07-25T00:18:20","slug":"cartago-do-grupo-grendene-celebra-a-paternidade-ativa","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/","title":{"rendered":"Cartago do grupo Grendene celebra a paternidade ativa"},"content":{"rendered":"\n<p>A Cartago, marca de sand\u00e1lias masculinas da Grendene, apresenta sua nova campanha para o Dia dos Pais focada na paternidade ativa. Com o tema <em>Pai que compartilha, transforma<\/em>; a ideia foi trazer a transforma\u00e7\u00e3o do \u201cser\u201d pai, mostrar a import\u00e2ncia e o papel do homem que cuida, educa e ensina, junto a diversidade de estilos e a busca pelo conforto, durabilidade e um bom custo-benef\u00edcio.<\/p>\n\n\n\n<p>Ser\u00e3o seis modelos diferentes de chinelo de dedo, que \u00e9 garantia de um mix de conforto e sofistica\u00e7\u00e3o, \u2013 com pre\u00e7os que v\u00e3o de R$59,99 a R$79,99. Vers\u00e1teis, os cal\u00e7ados se adequam a distintas ocasi\u00f5es e territ\u00f3rios, sejam eles Casual Elegante, que traduzem elementos da moda para o dia a dia, de forma minimalista; Casual Cl\u00e1ssico, onde a inspira\u00e7\u00e3o vem do tradicional ou Casual Esportivo, que equilibra toques de cores com estilo moderno.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/07\/cartago_grendene_02.jpg\" alt=\"\" class=\"wp-image-25985\" width=\"696\" height=\"456\"\/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Tr\u00eas nomes que seguem e compartilham a paternidade ativa foram escolhidos para estrelar a campanha. S\u00e3o eles: o ator Julio Rocha, o criador de conte\u00fado Thiago Queiroz (<a href=\"https:\/\/www.instagram.com\/paizinhovirgulaoficial\/\" target=\"_blank\" rel=\"noreferrer noopener\">@paizinhovirgulaoficial<\/a>) e o jornalista Manoel Soares. Eles dar\u00e3o vida a toda a versatilidade dos produtos Cartago atrav\u00e9s de conte\u00fados pr\u00f3prios, que ir\u00e3o refletir o lifestyle de cada um e suas a\u00e7\u00f5es, cuidados f\u00edsicos e emocionais com seus filhos, mostrando como ser um pai ativo pode fazer diferen\u00e7a na vida e no crescimento, da crian\u00e7a e na sua pr\u00f3pria. \u00a0<\/p>\n\n\n\n<p>A campanha ser\u00e1 lan\u00e7ada no dia 22.07 nas redes da Cartago e dos influenciadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Cartago, marca de sand\u00e1lias masculinas da Grendene, apresenta sua nova campanha para o Dia dos Pais focada na paternidade ativa. Com o tema Pai que compartilha, transforma; a ideia foi trazer a transforma\u00e7\u00e3o do \u201cser\u201d pai, mostrar a import\u00e2ncia e o papel do homem que cuida, educa e ensina, junto a diversidade de estilos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6],"tags":[65,4137,33,28],"class_list":["post-25983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-campanha","tag-cartago","tag-estrategia","tag-marketing"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartago do grupo Grendene celebra a paternidade ativa - CidadeMarketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartago do grupo Grendene celebra a paternidade ativa - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"A Cartago, marca de sand\u00e1lias masculinas da Grendene, apresenta sua nova campanha para o Dia dos Pais focada na paternidade ativa. Com o tema Pai que compartilha, transforma; a ideia foi trazer a transforma\u00e7\u00e3o do \u201cser\u201d pai, mostrar a import\u00e2ncia e o papel do homem que cuida, educa e ensina, junto a diversidade de estilos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-25T00:18:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-25T00:18:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/07\/cartago_grendene.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2295\" \/>\n\t<meta property=\"og:image:height\" content=\"1531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"Cartago do grupo Grendene celebra a paternidade ativa\",\"datePublished\":\"2021-07-25T00:18:17+00:00\",\"dateModified\":\"2021-07-25T00:18:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/\"},\"wordCount\":270,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cartago_grendene.jpg\",\"keywords\":[\"campanha\",\"Cartago\",\"estrat\u00e9gia\",\"marketing\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/\",\"name\":\"Cartago do grupo Grendene celebra a paternidade ativa - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cartago_grendene.jpg\",\"datePublished\":\"2021-07-25T00:18:17+00:00\",\"dateModified\":\"2021-07-25T00:18:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cartago_grendene.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cartago_grendene.jpg\",\"width\":2295,\"height\":1531,\"caption\":\"Thiago Queiroz (@paizinhovirgulaoficial) para Cartago\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/07\\\/24\\\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartago do grupo Grendene celebra a paternidade ativa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cartago do grupo Grendene celebra a paternidade ativa - CidadeMarketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/","og_locale":"pt_BR","og_type":"article","og_title":"Cartago do grupo Grendene celebra a paternidade ativa - CidadeMarketing","og_description":"A Cartago, marca de sand\u00e1lias masculinas da Grendene, apresenta sua nova campanha para o Dia dos Pais focada na paternidade ativa. Com o tema Pai que compartilha, transforma; a ideia foi trazer a transforma\u00e7\u00e3o do \u201cser\u201d pai, mostrar a import\u00e2ncia e o papel do homem que cuida, educa e ensina, junto a diversidade de estilos [&hellip;]","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2021-07-25T00:18:17+00:00","article_modified_time":"2021-07-25T00:18:20+00:00","og_image":[{"width":2295,"height":1531,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/07\/cartago_grendene.jpg","type":"image\/jpeg"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"Cartago do grupo Grendene celebra a paternidade ativa","datePublished":"2021-07-25T00:18:17+00:00","dateModified":"2021-07-25T00:18:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/"},"wordCount":270,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/07\/cartago_grendene.jpg","keywords":["campanha","Cartago","estrat\u00e9gia","marketing"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/","name":"Cartago do grupo Grendene celebra a paternidade ativa - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/07\/cartago_grendene.jpg","datePublished":"2021-07-25T00:18:17+00:00","dateModified":"2021-07-25T00:18:20+00:00","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/07\/cartago_grendene.jpg","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/07\/cartago_grendene.jpg","width":2295,"height":1531,"caption":"Thiago Queiroz (@paizinhovirgulaoficial) para Cartago"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/07\/24\/cartago-do-grupo-grendene-celebra-a-paternidade-ativa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"Cartago do grupo Grendene celebra a paternidade ativa"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/25983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=25983"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/25983\/revisions"}],"predecessor-version":[{"id":25986,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/25983\/revisions\/25986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/25984"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=25983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=25983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=25983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}