{"id":22848,"date":"2021-03-26T22:32:07","date_gmt":"2021-03-27T01:32:07","guid":{"rendered":"https:\/\/www.cidademarketing.com.br\/marketing\/?p=22848"},"modified":"2021-03-26T22:32:09","modified_gmt":"2021-03-27T01:32:09","slug":"alihouse-une-record-e-sbt-em-acao-inedita","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/","title":{"rendered":"AliHouse une Record e SBT em a\u00e7\u00e3o in\u00e9dita"},"content":{"rendered":"\n<p>Uma a\u00e7\u00e3o de entretenimento in\u00e9dita no varejo, inspirada nos programas de <em>reality show e <\/em>comandada por duas das maiores estrelas da TV brasileira, Sabrina Sato e Eliana, reunir\u00e1 <strong>Record<\/strong>, <strong>SBT<\/strong> e plataformas de transmiss\u00e3o online. Trata-se do <strong>AliHouse<\/strong>, a\u00e7\u00e3o veiculada, ao mesmo tempo, pelas emissoras e plataformas. A atra\u00e7\u00e3o compartilha ainda nomes consagrados como os apresentadores Cear\u00e1, Carioca, Beto Hora e Benja, e leva ao ar uma competi\u00e7\u00e3o envolvendo os comediantes Rodrigo Capella, Mhel Marrer, Marcelo Zangrandi, Pri Castello Branco, Victor Sarro e Cris Paiva.&nbsp;<\/p>\n\n\n\n<p>AliHouse ser\u00e1 transmitido, diariamente, em hor\u00e1rio nobre, entre os dias 29 de mar\u00e7o e 2 de abril, semana que marca o anivers\u00e1rio de 11 anos da plataforma AliExpress. Ao fim de cada epis\u00f3dio transmitido em TV aberta, os artistas participar\u00e3o de uma transmiss\u00e3o online ao vivo, via Youtube do AliExpress, da Record e do SBT, al\u00e9m do Instagram do AliExpress, com <em>games<\/em> e intera\u00e7\u00f5es.&nbsp;&nbsp; &nbsp;<\/p>\n\n\n\n<p>Criado pela ag\u00eancia <strong>EnergyBBDO<\/strong>, em parceria com a Record e com o SBT Solutions, o projeto une entretenimento, conte\u00fado e ofertas especiais na plataforma do AliExpress, que \u00e9 o maior site de compras internacionaisdo mundo, em comemora\u00e7\u00e3o ao seu 11\u00ba ano de opera\u00e7\u00e3o no Brasil.&nbsp;<\/p>\n\n\n\n<p>A\u00e7\u00f5es como essa de <em>shoppertainment<\/em> fazem parte do DNA do Alibaba, grupo ao qual o AliExpress pertence. \u201cProcuramos adaptar \u00e0s caracter\u00edsticas brasileiras nosso <em>expertise <\/em>mundial em misturar divers\u00e3o e vendas, modelo consagrado pelo Alibaba nos festivais de compras que promove pelo mundo\u201d, afirma Yan Di, <em>country manager<\/em> do AliExpress no Brasil.&nbsp; &nbsp;<\/p>\n\n\n\n<p>\u201cTer novamente o AliExpress como anunciante do Grupo Record \u00e9 motivo de extrema alegria e de satisfa\u00e7\u00e3o para todos n\u00f3s. Esse retorno demonstra a satisfa\u00e7\u00e3o do cliente em rela\u00e7\u00e3o aos resultados alcan\u00e7ados pela sua participa\u00e7\u00e3o na Fazenda\u201920, atesta a confian\u00e7a depositada na minha equipe comercial, que fez um excelente trabalho, e aponta a atratividade da nossa grade de programa\u00e7\u00e3o, o poder de engajamento do nosso elenco, al\u00e9m da for\u00e7a e da influ\u00eancia dos nossos canais de comunica\u00e7\u00e3o\u201d, afirma Walter Zagari, vice-presidente Comercial, Marketing e Multiplataforma do Grupo Record. \u201cGostaria tamb\u00e9m de destacar a uni\u00e3o e a sinergia das compet\u00eancias art\u00edsticas e comerciais do Grupo Record e do SBT para a realiza\u00e7\u00e3o deste projeto. Esse modelo de neg\u00f3cio focado no trabalho em conjunto entre as Redes, apesar de pouco usual, no meu ponto de vista deveria ser mais explorado por ser totalmente ben\u00e9fico \u00e0s emissoras, que ampliam seu portf\u00f3lio de vendas, \u00e0s iniciativas multiplataforma e tamb\u00e9m por potencializar os resultados dos clientes, que dependendo da estrat\u00e9gia de comunica\u00e7\u00e3o impactam p\u00fablicos distintos e t\u00eam sua penetra\u00e7\u00e3o ampliada\u201d, conclui. &nbsp;<\/p>\n\n\n\n<p><strong>A din\u00e2mica<\/strong><\/p>\n\n\n\n<p><strong><br><\/strong>AliHouse, a casa mais compr\u00e1vel do Brasil, ter\u00e1 cinco c\u00f4modos ambientados com produtos \u00e0 venda no AliExpress \u2013 cada produto exibe um QR code que leva ao link onde eles podem ser comprados, no site ou app da plataforma. A cada Live, dois comediantes participar\u00e3o de uma competi\u00e7\u00e3o onde precisar\u00e3o utilizar esses itens em miss\u00f5es como cozinhar ou praticar um esporte, por exemplo. Mas, enquanto realizam as provas, os produtos que forem sendo comprados no site ser\u00e3o retirados do c\u00f4modo, e os participantes precisar\u00e3o encontrar alternativas para completarem a miss\u00e3o sem eles. A cada epis\u00f3dio ser\u00e3o conhecidos os vencedores de cada competi\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p><br>Os itens exibidos na TV e Lives estar\u00e3o \u00e0 venda para o p\u00fablico geral com pre\u00e7os especiais. Durante as transmiss\u00f5es, ser\u00e3o divulgados cupons que oferecem US$ 4 de desconto (cerca de R$ 22) em compras acima de US$ 5 (cerca de R$ 27,50). Al\u00e9m disso, promo\u00e7\u00f5es-surpresa ser\u00e3o anunciadas exclusivamente nas Lives.&nbsp;<\/p>\n\n\n\n<p>&#8220;AliHouse \u00e9 o tipo de trabalho que nos d\u00e1 muito orgulho de fazer, pois coloca praticamente todo o time da ag\u00eancia em colabora\u00e7\u00e3o com duas grandes empresas, Record e SBT, al\u00e9m da Clapme e Dromed\u00e1rio, que foram nossos parceiros no desenvolvimento, produ\u00e7\u00e3o e transmiss\u00e3o dos conte\u00fados. A atua\u00e7\u00e3o de nossa equipe, plugada a terceiros desde o in\u00edcio do trabalho, \u00e9 o modelo que sempre buscamos para a EnergyBBDO\u201d, afirma Alexandre Pagano, diretor executivo de cria\u00e7\u00e3o da ag\u00eancia. &nbsp;<\/p>\n\n\n\n<p><strong><u>Ficha T\u00e9cnica<\/u><\/strong><strong>&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ag\u00eancia<\/strong>: Energy BBDO&nbsp;<\/p>\n\n\n\n<p><strong>Anunciante<\/strong>: AliExpress&nbsp;<\/p>\n\n\n\n<p><strong>Produto<\/strong>: Anivers\u00e1rio 11 anos&nbsp;<\/p>\n\n\n\n<p><strong>T\u00edtulos<\/strong>: AliHouse&nbsp;<\/p>\n\n\n\n<p><strong>Managing Director<\/strong>: Daniel Baena&nbsp;<\/p>\n\n\n\n<p><strong>Diretores Executivos de Cria\u00e7\u00e3o<\/strong>: Alexandre Pagano e Jo\u00e3o Caetano Brasil&nbsp;<\/p>\n\n\n\n<p><strong>Cria\u00e7\u00e3o<\/strong>: Guilherme Portugal, Lucas Saicali, Isabela Priante e Felipe Oliveira&nbsp;<\/p>\n\n\n\n<p><strong>Atendimento<\/strong>: Gisele Pansera, Renato Nose, Gabriella de Souza e Guilherme Marraccini&nbsp;<\/p>\n\n\n\n<p><strong>Planejamento<\/strong>: Jos\u00e9 Lucas de Paula&nbsp;e&nbsp;Renato Muller&nbsp;<\/p>\n\n\n\n<p><strong>Innovation and connections: <\/strong>Rafael Amorim&nbsp;<\/p>\n\n\n\n<p><strong>M\u00eddia:<\/strong>&nbsp;Marcelo Marujo, Roberta Jablonski, Guilherme Felix, Laura Ramos, Rafael Vizona e Beatriz Campos&nbsp;<\/p>\n\n\n\n<p><strong>Produ\u00e7\u00e3o Integrada<\/strong>: Celso Groba, S\u00e9rgio Costa e Claudia Rocha&nbsp;<\/p>\n\n\n\n<p><strong>Produ\u00e7\u00e3o de conte\u00fado: <\/strong>Dromed\u00e1rio<\/p>\n\n\n\n<p><strong>Produtora filme<\/strong>: Record, SBT e ClapMe&nbsp;<\/p>\n\n\n\n<p><strong>Dire\u00e7\u00e3o<\/strong>: Andr\u00e9 Germiniani&nbsp;<\/p>\n\n\n\n<p><strong>Diretor de Fotografia<\/strong>: Andr\u00e9 Germiniani&nbsp;<\/p>\n\n\n\n<p><strong>Produ\u00e7\u00e3o Executiva<\/strong>: Carol Marimon&nbsp;<\/p>\n\n\n\n<p><strong>Atendimento: <\/strong>Lucas Borges&nbsp;<\/p>\n\n\n\n<p><strong>P\u00f3s-produ\u00e7\u00e3o<\/strong>: Vin\u00edcius Ankerkrone&nbsp;<\/p>\n\n\n\n<p><strong>Edi\u00e7\u00e3o: Pedro Almeida&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Trilha sonora:<\/strong> ClapMe&nbsp;<\/p>\n\n\n\n<p><strong>Sound Design e Mixagem<\/strong>: Leonardo Nicolosi&nbsp;<\/p>\n\n\n\n<p><strong>Dire\u00e7\u00e3o de arte e cenografia:<\/strong> Michelly Thomaz&nbsp;<\/p>\n\n\n\n<p><strong>Assistente e Produ\u00e7\u00e3o de arte:<\/strong> Fernanda Cuenca &nbsp;<\/p>\n\n\n\n<p><strong>Produ\u00e7\u00e3o de objetos:<\/strong> Jamaica Santarem &nbsp;<\/p>\n\n\n\n<p><strong>Cenot\u00e9cnicos:<\/strong> Thiago Ara\u00fajo e Pedro Milan&nbsp;<\/p>\n\n\n\n<p><strong>Assistentes de cenot\u00e9cnica:<\/strong> Guilherme Moraes e Samuel Luis Borges &nbsp;<\/p>\n\n\n\n<p><strong>Ajudante arte:<\/strong> Marcelo Mattina&nbsp;<\/p>\n\n\n\n<p><strong>Motorista:<\/strong> Jefferson de Azevedo&nbsp;<\/p>\n\n\n\n<p><strong>Aprova\u00e7\u00e3o cliente<\/strong>: Christina Lu, Prasanna Ashok Bhavsar, Eric Sun, Sara Zheng e Yan Di&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma a\u00e7\u00e3o de entretenimento in\u00e9dita no varejo, inspirada nos programas de reality show e comandada por duas das maiores estrelas da TV brasileira, Sabrina Sato e Eliana, reunir\u00e1 Record, SBT e plataformas de transmiss\u00e3o online. Trata-se do AliHouse, a\u00e7\u00e3o veiculada, ao mesmo tempo, pelas emissoras e plataformas. A atra\u00e7\u00e3o compartilha ainda nomes consagrados como os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6],"tags":[3765,3766,28,2595,418],"class_list":["post-22848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-aliexpress","tag-alihouse","tag-marketing","tag-record","tag-sbt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AliHouse une Record e SBT em a\u00e7\u00e3o in\u00e9dita - CidadeMarketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AliHouse une Record e SBT em a\u00e7\u00e3o in\u00e9dita - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"Uma a\u00e7\u00e3o de entretenimento in\u00e9dita no varejo, inspirada nos programas de reality show e comandada por duas das maiores estrelas da TV brasileira, Sabrina Sato e Eliana, reunir\u00e1 Record, SBT e plataformas de transmiss\u00e3o online. Trata-se do AliHouse, a\u00e7\u00e3o veiculada, ao mesmo tempo, pelas emissoras e plataformas. A atra\u00e7\u00e3o compartilha ainda nomes consagrados como os [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-27T01:32:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-27T01:32:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/03\/Foto-AliHouse-apresentadores_-1280x853_P.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"AliHouse une Record e SBT em a\u00e7\u00e3o in\u00e9dita\",\"datePublished\":\"2021-03-27T01:32:07+00:00\",\"dateModified\":\"2021-03-27T01:32:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/\"},\"wordCount\":977,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Foto-AliHouse-apresentadores_-1280x853_P.jpg\",\"keywords\":[\"AliExpress\",\"AliHouse\",\"marketing\",\"Record\",\"SBT\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/\",\"name\":\"AliHouse une Record e SBT em a\u00e7\u00e3o in\u00e9dita - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Foto-AliHouse-apresentadores_-1280x853_P.jpg\",\"datePublished\":\"2021-03-27T01:32:07+00:00\",\"dateModified\":\"2021-03-27T01:32:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Foto-AliHouse-apresentadores_-1280x853_P.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Foto-AliHouse-apresentadores_-1280x853_P.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/03\\\/26\\\/alihouse-une-record-e-sbt-em-acao-inedita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AliHouse une Record e SBT em a\u00e7\u00e3o in\u00e9dita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AliHouse une Record e SBT em a\u00e7\u00e3o in\u00e9dita - CidadeMarketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/","og_locale":"pt_BR","og_type":"article","og_title":"AliHouse une Record e SBT em a\u00e7\u00e3o in\u00e9dita - CidadeMarketing","og_description":"Uma a\u00e7\u00e3o de entretenimento in\u00e9dita no varejo, inspirada nos programas de reality show e comandada por duas das maiores estrelas da TV brasileira, Sabrina Sato e Eliana, reunir\u00e1 Record, SBT e plataformas de transmiss\u00e3o online. Trata-se do AliHouse, a\u00e7\u00e3o veiculada, ao mesmo tempo, pelas emissoras e plataformas. A atra\u00e7\u00e3o compartilha ainda nomes consagrados como os [&hellip;]","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2021-03-27T01:32:07+00:00","article_modified_time":"2021-03-27T01:32:09+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/03\/Foto-AliHouse-apresentadores_-1280x853_P.jpg","type":"image\/jpeg"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"AliHouse une Record e SBT em a\u00e7\u00e3o in\u00e9dita","datePublished":"2021-03-27T01:32:07+00:00","dateModified":"2021-03-27T01:32:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/"},"wordCount":977,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/03\/Foto-AliHouse-apresentadores_-1280x853_P.jpg","keywords":["AliExpress","AliHouse","marketing","Record","SBT"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/","name":"AliHouse une Record e SBT em a\u00e7\u00e3o in\u00e9dita - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/03\/Foto-AliHouse-apresentadores_-1280x853_P.jpg","datePublished":"2021-03-27T01:32:07+00:00","dateModified":"2021-03-27T01:32:09+00:00","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/03\/Foto-AliHouse-apresentadores_-1280x853_P.jpg","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/03\/Foto-AliHouse-apresentadores_-1280x853_P.jpg","width":1280,"height":853,"caption":"Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/03\/26\/alihouse-une-record-e-sbt-em-acao-inedita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"AliHouse une Record e SBT em a\u00e7\u00e3o in\u00e9dita"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/22848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=22848"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/22848\/revisions"}],"predecessor-version":[{"id":22850,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/22848\/revisions\/22850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/22849"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=22848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=22848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=22848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}