{"id":22214,"date":"2021-02-23T22:53:32","date_gmt":"2021-02-24T01:53:32","guid":{"rendered":"https:\/\/www.cidademarketing.com.br\/marketing\/?p=22214"},"modified":"2021-02-23T22:53:35","modified_gmt":"2021-02-24T01:53:35","slug":"tradersclub-apresenta-nova-diretora-de-marketing","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/","title":{"rendered":"TradersClub apresenta nova diretora de marketing"},"content":{"rendered":"\n<p>O TC, a plataforma de intelig\u00eancia e informa\u00e7\u00e3o do investidor pessoa f\u00edsica, acaba de anunciar a contrata\u00e7\u00e3o de Cristianne Alves, experiente profissional do mercado, para a \u00e1rea estrat\u00e9gica de Marketing. H\u00e1 mais de 10 anos atuando nas \u00e1reas de Marketing e Comunica\u00e7\u00e3o Corporativa de grandes empresas, a nova diretora de Marketing do TC \u00e9 especializada em constru\u00e7\u00e3o e prote\u00e7\u00e3o de marcas.<\/p>\n\n\n\n<p>Com sua expertise, Cristianne foi respons\u00e1vel por fazer a gest\u00e3o de grandes marcas como PicPay, com aplica\u00e7\u00e3o de planos estrat\u00e9gicos de comunica\u00e7\u00e3o integrada 360\u00ba. Tamb\u00e9m liderou as equipes de Marketing das unidades da Thomson Reuters na Am\u00e9rica Latina, sendo respons\u00e1vel pela implanta\u00e7\u00e3o, em S\u00e3o Paulo, do 1\u00ba Laborat\u00f3rio de Inova\u00e7\u00e3o promovido pela multinacional na regi\u00e3o. A diretora de Marketing tamb\u00e9m \u00e9 cofundadora da Histeria Games e respons\u00e1vel pelas frentes de go-to-market, comunica\u00e7\u00e3o corporativa e rela\u00e7\u00f5es com investidores da startup.<\/p>\n\n\n\n<p>&#8220;Vivemos um momento \u00fanico no mercado financeiro, com uma grande quantidade de pessoas entrando no universo dos investimentos. No Brasil, 1,5 milh\u00e3o de investidores ingressaram na bolsa apenas em 2020. Ent\u00e3o ter uma profissional como a Cristianne na empresa \u00e9 essencial para acelerarmos na nossa miss\u00e3o de trazer novos investidores para o mercado de capitais, com responsabilidade e promovendo inova\u00e7\u00e3o na vida das pessoas, al\u00e9m de estreitar a comunica\u00e7\u00e3o com os nossos usu\u00e1rios&#8221;, afirma Pedro Albuquerque, CEO do TC.<\/p>\n\n\n\n<p>Com MBA em Marketing Management pelo Ibmec Business School, Cristianne Alves tem a miss\u00e3o de contribuir com a penetra\u00e7\u00e3o do TC no Pa\u00eds, al\u00e9m de fortalecer e posicionar o neg\u00f3cio como uma empresa que viabiliza a democratiza\u00e7\u00e3o do acesso \u00e0s informa\u00e7\u00f5es sobre o mercado financeiro.<\/p>\n\n\n\n<p>\u201cChego motivada com o desafio de estruturar e conduzir a estrat\u00e9gia de expans\u00e3o e ganho de escala do TC, a <em>fintech<\/em> no modelo SaaS (<em>software<\/em> como servi\u00e7o) que mais cresce no Pa\u00eds. Nosso time est\u00e1 empenhado em construir mensagens e iniciativas que, al\u00e9m de gerar <em>awareness<\/em> para a marca nesse mercado em ebuli\u00e7\u00e3o, engajem o maior n\u00famero de pessoas na busca por conhecimento e mudan\u00e7a real em suas vidas financeiras\u201d, conta Alves.<\/p>\n\n\n\n<p>Hoje, a estrutura de Marketing do TC \u00e9 formada por mais de 30 colaboradores e segue em crescimento, contando com pilares de Performance, Product Marketing, Branding e Cria\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O TC, a plataforma de intelig\u00eancia e informa\u00e7\u00e3o do investidor pessoa f\u00edsica, acaba de anunciar a contrata\u00e7\u00e3o de Cristianne Alves, experiente profissional do mercado, para a \u00e1rea estrat\u00e9gica de Marketing. H\u00e1 mais de 10 anos atuando nas \u00e1reas de Marketing e Comunica\u00e7\u00e3o Corporativa de grandes empresas, a nova diretora de Marketing do TC \u00e9 especializada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6],"tags":[33,28,3705],"class_list":["post-22214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-estrategia","tag-marketing","tag-tradersclub"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TradersClub apresenta nova diretora de marketing - CidadeMarketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TradersClub apresenta nova diretora de marketing - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"O TC, a plataforma de intelig\u00eancia e informa\u00e7\u00e3o do investidor pessoa f\u00edsica, acaba de anunciar a contrata\u00e7\u00e3o de Cristianne Alves, experiente profissional do mercado, para a \u00e1rea estrat\u00e9gica de Marketing. H\u00e1 mais de 10 anos atuando nas \u00e1reas de Marketing e Comunica\u00e7\u00e3o Corporativa de grandes empresas, a nova diretora de Marketing do TC \u00e9 especializada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-24T01:53:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-24T01:53:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/02\/TradersClub_marketing-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1662\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"TradersClub apresenta nova diretora de marketing\",\"datePublished\":\"2021-02-24T01:53:32+00:00\",\"dateModified\":\"2021-02-24T01:53:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/\"},\"wordCount\":408,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/TradersClub_marketing-scaled.jpg\",\"keywords\":[\"estrat\u00e9gia\",\"marketing\",\"TradersClub\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/\",\"name\":\"TradersClub apresenta nova diretora de marketing - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/TradersClub_marketing-scaled.jpg\",\"datePublished\":\"2021-02-24T01:53:32+00:00\",\"dateModified\":\"2021-02-24T01:53:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/TradersClub_marketing-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/TradersClub_marketing-scaled.jpg\",\"width\":1662,\"height\":2560,\"caption\":\"Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/23\\\/tradersclub-apresenta-nova-diretora-de-marketing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TradersClub apresenta nova diretora de marketing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TradersClub apresenta nova diretora de marketing - CidadeMarketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/","og_locale":"pt_BR","og_type":"article","og_title":"TradersClub apresenta nova diretora de marketing - CidadeMarketing","og_description":"O TC, a plataforma de intelig\u00eancia e informa\u00e7\u00e3o do investidor pessoa f\u00edsica, acaba de anunciar a contrata\u00e7\u00e3o de Cristianne Alves, experiente profissional do mercado, para a \u00e1rea estrat\u00e9gica de Marketing. H\u00e1 mais de 10 anos atuando nas \u00e1reas de Marketing e Comunica\u00e7\u00e3o Corporativa de grandes empresas, a nova diretora de Marketing do TC \u00e9 especializada [&hellip;]","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2021-02-24T01:53:32+00:00","article_modified_time":"2021-02-24T01:53:35+00:00","og_image":[{"width":1662,"height":2560,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/02\/TradersClub_marketing-scaled.jpg","type":"image\/jpeg"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"TradersClub apresenta nova diretora de marketing","datePublished":"2021-02-24T01:53:32+00:00","dateModified":"2021-02-24T01:53:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/"},"wordCount":408,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/02\/TradersClub_marketing-scaled.jpg","keywords":["estrat\u00e9gia","marketing","TradersClub"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/","name":"TradersClub apresenta nova diretora de marketing - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/02\/TradersClub_marketing-scaled.jpg","datePublished":"2021-02-24T01:53:32+00:00","dateModified":"2021-02-24T01:53:35+00:00","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/02\/TradersClub_marketing-scaled.jpg","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/02\/TradersClub_marketing-scaled.jpg","width":1662,"height":2560,"caption":"Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/23\/tradersclub-apresenta-nova-diretora-de-marketing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"TradersClub apresenta nova diretora de marketing"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/22214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=22214"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/22214\/revisions"}],"predecessor-version":[{"id":22216,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/22214\/revisions\/22216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/22215"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=22214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=22214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=22214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}