{"id":22154,"date":"2021-02-21T09:01:24","date_gmt":"2021-02-21T12:01:24","guid":{"rendered":"https:\/\/www.cidademarketing.com.br\/marketing\/?p=22154"},"modified":"2021-02-21T09:01:27","modified_gmt":"2021-02-21T12:01:27","slug":"em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/","title":{"rendered":"Em campanha de consumo consciente, P\u00e3o de A\u00e7\u00facar convida consumidores para o movimento &#8220;Cada Dia Conta&#8221;"},"content":{"rendered":"\n<p>O P\u00e3o de A\u00e7\u00facar tem como prop\u00f3sito estimular a pr\u00e1tica da felicidade por meio das rela\u00e7\u00f5es e do alimento e por isso a rede acaba de lan\u00e7ar a campanha &#8220;Cada Dia Conta&#8221;, que convida as pessoas a se engajarem sobre a import\u00e2ncia de um movimento coletivo de consumo consciente e de mudan\u00e7as de atitudes di\u00e1rias individuais e coletivas para a constru\u00e7\u00e3o de um futuro mais sustent\u00e1vel.<\/p>\n\n\n\n<p>O objetivo \u00e9 trazer mais conhecimento e mobiliza\u00e7\u00e3o de clientes e sociedade sobre temas ambientais que parecem estar distantes do dia a dia, mas que est\u00e3o totalmente conectados, por exemplo, a quest\u00e3o das mudan\u00e7as clim\u00e1ticas, o consumo de recursos naturais com o chamado <strong>Dia da Sobrecarga da Terra<\/strong>. Ainda pouco difundida no Brasil, a data representa o momento em que passamos a demandar mais recursos naturais do que a Terra \u00e9 capaz de regenerar em um ano. Em 2019 e 2020, a data aconteceu em 29 de julho e 22 de agosto, respectivamente.<\/p>\n\n\n\n<p>Para o lan\u00e7amento do projeto, constru\u00eddo em parceria com a BETC\/Havas, a rede lan\u00e7ao filme &#8220;#CadaDiaConta, pequenas atitudes por um planeta mais leve&#8221; que destaca, na pr\u00e1tica, quais mudan\u00e7as de atitudes di\u00e1rias impactam em transforma\u00e7\u00f5es coletivas e a import\u00e2ncia do envolvimento de todos para a mudan\u00e7a acontecer. O v\u00eddeo est\u00e1 dispon\u00edvel no canal da rede no Youtube e nas m\u00eddias sociais e contar\u00e1 com o lan\u00e7amento de diversos &#8220;stickers&#8221; para o Instagram, como #cadadiaconta, #cadaatitudeconta, 100% org\u00e2nico, entre outros.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>A ideia \u00e9 que a campanha seja perene, por este motivo, ao longo do ano, a rede lan\u00e7ar\u00e1 outras iniciativas para refor\u00e7ar o conceito da campanha no dia a dia das pessoas, conscientizando sobre pequenas atitudes por um planeta mais feliz.<\/p>\n\n\n\n<p>J\u00e1 para os clientes do e-commerce, a campanha prop\u00f5e um upcycling nas ecobags existentes em suas casas. A a\u00e7\u00e3o ser\u00e1 feita com a disponibiliza\u00e7\u00e3o de adesivos para que os consumidores possam customizar suas sacolas retorn\u00e1veis com o tema da campanha.<\/p>\n\n\n\n<p>&#8220;Com o &#8220;Cada Dia Conta&#8221;, queremos refor\u00e7ar nosso papel na sociedade como agente transformador, incentivando a\u00e7\u00f5es educativas para uma produ\u00e7\u00e3o e um consumo mais consciente e sustent\u00e1vel &#8220;, diz Camila Assis, gerente de marketing do P\u00e3o de A\u00e7\u00facar.<\/p>\n\n\n\n<p>&#8220;Hoje, temos diversas iniciativas que contribuem para que os consumidores tenham em seu dia a dia pr\u00e1ticas mais sustent\u00e1veis como os programas de reciclagem e log\u00edstica reversa, a oferta de produtos org\u00e2nicos, prote\u00ednas contemplam bem-estar animal na sua produ\u00e7\u00e3o, a\u00e7\u00f5es de combate ao desperd\u00edcio, como a doa\u00e7\u00e3o de alimentos, entre outros. A a\u00e7\u00e3o de cada um \u00e9 importante, mas \u00e9 a a\u00e7\u00e3o conjunta de todos que vai realmente nos transformar e transformar nossa sociedade&#8221;, completa Eduardo Telles, Diretor de Marketing do GPA.<\/p>\n\n\n\n<p>O movimento tem o apoio do Instituto Akatu, ONG pioneira no trabalho de sensibilizar e mobilizar a sociedade para o consumo consciente, e que \u00e9 respons\u00e1vel pela cria\u00e7\u00e3o de conte\u00fados que estar\u00e3o dispon\u00edveis no blog do P\u00e3o.<\/p>\n\n\n\n<p>&#8220;A transi\u00e7\u00e3o para estilos de vida mais saud\u00e1veis e sustent\u00e1veis s\u00f3 ser\u00e1 poss\u00edvel se todos os atores da sociedade agirem nesta mesma dire\u00e7\u00e3o. Essa campanha do P\u00e3o de A\u00e7\u00facar \u00e9 um exemplo de iniciativa que as empresas podem fazer para ajudar os consumidores a perceberem que a ado\u00e7\u00e3o de simples pr\u00e1ticas de consumo consciente pode gerar um melhor impacto para eles mesmos, o meio ambiente e a sociedade em geral, principalmente quando essas pr\u00e1ticas se tornam h\u00e1bitos. Para o Akatu, \u00e9 uma grande alegria ser parceiro da campanha contribuindo com informa\u00e7\u00f5es sobre o Dia da Sobrecarga da Terra, uma data que deixa como recado a urgente necessidade de adotar padr\u00f5es mais sustent\u00e1veis de produ\u00e7\u00e3o e consumo&#8221;, diz Bruna Tiussu, gerente de Comunica\u00e7\u00e3o e Conte\u00fados do Instituto Akatu.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"a3AlrAOItzA\"><iframe title=\"#CadaDiaConta, Pequenas atitudes por um planeta mais leve\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/a3AlrAOItzA?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Conhe\u00e7a algumas iniciativas do P\u00e3o de A\u00e7\u00facar para incentivar o tema:<\/strong><\/p>\n\n\n\n<p><strong>Lugar de Escuta<\/strong><\/p>\n\n\n\n<p>O P\u00e3o de A\u00e7\u00facar lan\u00e7ou recentemente o podcast &#8220;Lugar de Escuta&#8221;, espa\u00e7o para ampliar a conscientiza\u00e7\u00e3o e conhecimento sobre sustentabilidade, economia circular, bem-estar animal, mudan\u00e7as clim\u00e1ticas, desperd\u00edcio e outros assuntos em discuss\u00e3o pela sociedade, s\u00e3o mais de 10 epis\u00f3dios com convidados especialistas no assunto para debater e falar sobre o assunto. Conhe\u00e7a acessando <a href=\"https:\/\/open.spotify.com\/show\/21K0eqEe9a9hJ547bjPqiD?si=jeq4cPu3R36OVIkhkOXFyA&amp;nd=1\" target=\"_blank\" rel=\"noreferrer noopener\">este link.<\/a><\/p>\n\n\n\n<p><strong>Esta\u00e7\u00f5es de Reciclagem P\u00e3o de A\u00e7\u00facar Unilever<\/strong><\/p>\n\n\n\n<p>Desde 2001, a rede conta com as Esta\u00e7\u00f5es de Reciclagem P\u00e3o de A\u00e7\u00facar Unilever, desenvolvidas e implementadas em parceria entre as duas marcas, que recebem diariamente materiais recicl\u00e1veis como metal, papel, pl\u00e1stico, vidro e \u00f3leo de cozinha descartados pelos clientes. S\u00e3o, ao todo, 94 Esta\u00e7\u00f5es em opera\u00e7\u00e3o distribu\u00eddas em 20 cidades do Brasil. Em quase 20 anos, mais de 123 mil toneladas de res\u00edduos j\u00e1 foram encaminhadas \u00e0 reciclagem. Al\u00e9m das Esta\u00e7\u00f5es, nossas lojas s\u00e3o pontos de coleta de diversos materiais para reciclagem: c\u00e1psulas de caf\u00e9, isopor, pilhas e baterias, rolhas, vidro e etc. Clique <a href=\"https:\/\/ytiquoronteedxe.i-mpr.com\/link.php?code=bDpodHRwcyUzQSUyRiUyRmNvbnRlbnQucGFvZGVhY3VjYXIuY29tJTJGc3VzdGVudGFiaWxpZGFkZSUyRmVzdGFjb2VzLWRlLXJlY2ljbGFnZW0tcGFvLWRlLWFjdWNhcjoyMDc5OTE0NjI4OmNvbnRhdG9AY2lkYWRlbWFya2V0aW5nLmNvbS5icjo3NTE1MWM=\">aqui <\/a>para saber mais.<\/p>\n\n\n\n<p><strong>Substitui\u00e7\u00e3o de 100% de suas bandejas de hortifruti<\/strong><\/p>\n\n\n\n<p>Em 2019, o P\u00e3o de A\u00e7\u00facar tamb\u00e9m iniciou a substitui\u00e7\u00e3o de 100% de suas bandejas utilizadas em produtos de hortifr\u00fati (frutas, verduras e legumes) das marcas exclusivas Taeq e Qualit\u00e1 para uma solu\u00e7\u00e3o 100% biodegrad\u00e1vel.<\/p>\n\n\n\n<p><strong>Caras do Brasil<\/strong><\/p>\n\n\n\n<p>O P\u00e3o de A\u00e7\u00facar conta ainda com o programa &#8220;Caras do Brasil&#8221;. Criado em 1999, \u00e9 exclusivo da rede e tem o prop\u00f3sito de incentivar a pequena produ\u00e7\u00e3o alimentar sustent\u00e1vel, com foco em pequenos fornecedores de produtos representativos das diferentes culturas culin\u00e1rias regionais. Temos hoje parceria com 16 produtores e j\u00e1 disponibilizamos para os consumidores 28 produtos desta iniciativa, que tamb\u00e9m s\u00e3o poss\u00edveis de comprar pelo site do P\u00e3o. Tratam-se de sabores e saberes brasileiros de produtos t\u00edpicos de cada regi\u00e3o do Brasil e que t\u00eam sua capacidade produtiva, sua sazonalidade de produ\u00e7\u00e3o e suas marcas e propostas de valor respeitadas. Em 2020 tivemos um crescimento de mais de 50% em vendas nos produtos nas 20 lojas que os produtos est\u00e3o hoje. Saiba mais <a href=\"https:\/\/content.paodeacucar.com\/sustentabilidade\/caras-do-brasil-negocios-sustentaveis\" target=\"_blank\" rel=\"noreferrer noopener\">aqui <\/a>.<\/p>\n\n\n\n<p><strong>Horta Social Urbana<\/strong><\/p>\n\n\n\n<p>Com o apoio do P\u00e3o de A\u00e7\u00facar, por meio do Instituto GPA, a Horta Social Urbana oferece cursos profissionalizantes de agricultura e jardinagem para pessoas em situa\u00e7\u00e3o de vulnerabilidade. Com a compra dos produtos da Horta Social Urbana, dispon\u00edveis no P\u00e3o Ricardo Jafet (S\u00e3o Paulo), automaticamente o cliente j\u00e1 est\u00e1 apoiando o projeto. Nela, \u00e9 poss\u00edvel adquirir op\u00e7\u00f5es org\u00e2nicas e fresquinhas de alecrim, almeir\u00e3o, alface, beterraba, cebolinha, couve, escarola, salsinha, entre outras. Clique <a href=\"https:\/\/content.paodeacucar.com\/inovacao\/horta-social-urbana\" target=\"_blank\" rel=\"noreferrer noopener\">aqui <\/a>para mais informa\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O P\u00e3o de A\u00e7\u00facar tem como prop\u00f3sito estimular a pr\u00e1tica da felicidade por meio das rela\u00e7\u00f5es e do alimento e por isso a rede acaba de lan\u00e7ar a campanha &#8220;Cada Dia Conta&#8221;, que convida as pessoas a se engajarem sobre a import\u00e2ncia de um movimento coletivo de consumo consciente e de mudan\u00e7as de atitudes di\u00e1rias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6],"tags":[65,33,172],"class_list":["post-22154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-campanha","tag-estrategia","tag-pao-de-acucar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Em campanha de consumo consciente, P\u00e3o de A\u00e7\u00facar convida consumidores para o movimento &quot;Cada Dia Conta&quot; - CidadeMarketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Em campanha de consumo consciente, P\u00e3o de A\u00e7\u00facar convida consumidores para o movimento &quot;Cada Dia Conta&quot; - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"O P\u00e3o de A\u00e7\u00facar tem como prop\u00f3sito estimular a pr\u00e1tica da felicidade por meio das rela\u00e7\u00f5es e do alimento e por isso a rede acaba de lan\u00e7ar a campanha &#8220;Cada Dia Conta&#8221;, que convida as pessoas a se engajarem sobre a import\u00e2ncia de um movimento coletivo de consumo consciente e de mudan\u00e7as de atitudes di\u00e1rias [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-21T12:01:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-21T12:01:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/02\/cadadiaconta_paodeacucar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1186\" \/>\n\t<meta property=\"og:image:height\" content=\"602\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"Em campanha de consumo consciente, P\u00e3o de A\u00e7\u00facar convida consumidores para o movimento &#8220;Cada Dia Conta&#8221;\",\"datePublished\":\"2021-02-21T12:01:24+00:00\",\"dateModified\":\"2021-02-21T12:01:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/\"},\"wordCount\":1169,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cadadiaconta_paodeacucar.jpg\",\"keywords\":[\"campanha\",\"estrat\u00e9gia\",\"p\u00e3o de a\u00e7\u00facar\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/\",\"name\":\"Em campanha de consumo consciente, P\u00e3o de A\u00e7\u00facar convida consumidores para o movimento \\\"Cada Dia Conta\\\" - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cadadiaconta_paodeacucar.jpg\",\"datePublished\":\"2021-02-21T12:01:24+00:00\",\"dateModified\":\"2021-02-21T12:01:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cadadiaconta_paodeacucar.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cadadiaconta_paodeacucar.jpg\",\"width\":1186,\"height\":602,\"caption\":\"Reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2021\\\/02\\\/21\\\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Em campanha de consumo consciente, P\u00e3o de A\u00e7\u00facar convida consumidores para o movimento &#8220;Cada Dia Conta&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Em campanha de consumo consciente, P\u00e3o de A\u00e7\u00facar convida consumidores para o movimento \"Cada Dia Conta\" - CidadeMarketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/","og_locale":"pt_BR","og_type":"article","og_title":"Em campanha de consumo consciente, P\u00e3o de A\u00e7\u00facar convida consumidores para o movimento \"Cada Dia Conta\" - CidadeMarketing","og_description":"O P\u00e3o de A\u00e7\u00facar tem como prop\u00f3sito estimular a pr\u00e1tica da felicidade por meio das rela\u00e7\u00f5es e do alimento e por isso a rede acaba de lan\u00e7ar a campanha &#8220;Cada Dia Conta&#8221;, que convida as pessoas a se engajarem sobre a import\u00e2ncia de um movimento coletivo de consumo consciente e de mudan\u00e7as de atitudes di\u00e1rias [&hellip;]","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2021-02-21T12:01:24+00:00","article_modified_time":"2021-02-21T12:01:27+00:00","og_image":[{"width":1186,"height":602,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/02\/cadadiaconta_paodeacucar.jpg","type":"image\/jpeg"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"Em campanha de consumo consciente, P\u00e3o de A\u00e7\u00facar convida consumidores para o movimento &#8220;Cada Dia Conta&#8221;","datePublished":"2021-02-21T12:01:24+00:00","dateModified":"2021-02-21T12:01:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/"},"wordCount":1169,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/02\/cadadiaconta_paodeacucar.jpg","keywords":["campanha","estrat\u00e9gia","p\u00e3o de a\u00e7\u00facar"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/","name":"Em campanha de consumo consciente, P\u00e3o de A\u00e7\u00facar convida consumidores para o movimento \"Cada Dia Conta\" - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/02\/cadadiaconta_paodeacucar.jpg","datePublished":"2021-02-21T12:01:24+00:00","dateModified":"2021-02-21T12:01:27+00:00","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/02\/cadadiaconta_paodeacucar.jpg","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2021\/02\/cadadiaconta_paodeacucar.jpg","width":1186,"height":602,"caption":"Reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2021\/02\/21\/em-campanha-de-consumo-consciente-pao-de-acucar-convida-consumidores-para-o-movimento-cada-dia-conta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"Em campanha de consumo consciente, P\u00e3o de A\u00e7\u00facar convida consumidores para o movimento &#8220;Cada Dia Conta&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/22154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=22154"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/22154\/revisions"}],"predecessor-version":[{"id":22157,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/22154\/revisions\/22157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/22156"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=22154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=22154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=22154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}