{"id":17545,"date":"2020-08-06T10:29:35","date_gmt":"2020-08-06T13:29:35","guid":{"rendered":"https:\/\/www.cidademarketing.com.br\/marketing\/?p=17545"},"modified":"2020-08-06T10:29:37","modified_gmt":"2020-08-06T13:29:37","slug":"banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/","title":{"rendered":"Banco do Brasil traz campanha de Dia dos Pais que retrata novos h\u00e1bitos das rela\u00e7\u00f5es familiares"},"content":{"rendered":"\n<p>Conforme o mundo navega por um \u201cnormal\u201d muito diferente, muitas das a\u00e7\u00f5es que n\u00f3s estamos nos acostumando hoje ter\u00e3o um impacto duradouro nas vidas. Entre os destaques, est\u00e3o os novos h\u00e1bitos e intera\u00e7\u00f5es familiares, ainda mais pr\u00f3xima e intensa.&nbsp;<\/p>\n\n\n\n<p>Pensando nisso, o Banco do Brasil enaltece o surgimento de nova rela\u00e7\u00e3o entre pai e filhos em sua campanha de dia dos pais, assinada pela Lew\u2019Lara\\TBWA, com estreia agendada para hoje e com veicula\u00e7\u00e3o nacional em TV aberta e em canais por assinatura.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.youtube.com\/watch?v=VIXELB5iDuo\n<\/div><\/figure>\n\n\n\n<p>&#8220;<em>A gente quis trazer uma mensagem mais otimista nesse filme de Dia dos Pais, de conforto, mas tamb\u00e9m bastante consciente do momento que o mundo est\u00e1 passando. E trazemos uma reflex\u00e3o de que momentos dif\u00edceis podem trazer experi\u00eancias \u00fanicas e aprendizados<\/em>&#8220;, afirmou o gerente de solu\u00e7\u00f5es de publicidade do BB, Gustavo Tocantins.&nbsp;<\/p>\n\n\n\n<p>O isolamento social causou um ajuste r\u00e1pido em todas as \u00e1reas da vida, proporcionando novas formas de fazer coisas comuns e acelerando a ado\u00e7\u00e3o de outras. Com o aumento da conviv\u00eancia, as rela\u00e7\u00f5es familiares se intensificaram, foram aproximadas e tomaram novas formas. E o filme traz cenas de pais e filhos interagindo neste novo contexto, com a recupera\u00e7\u00e3o de h\u00e1bitos esquecidos e mais ainda nas oportunidades que esse momento proporcionou, seja na videoconfer\u00eancia do trabalho que o filho entra de surpresa, nas aventuras culin\u00e1rias, nas novas formas de matar as saudades de quem est\u00e1 longe via videoconfer\u00eancia, at\u00e9 mesmo nas aulas online dos filhos que os pais aproveitam para aprender algo novo.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"568\" src=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_02-1024x568.png\" alt=\"\" data-id=\"17546\" data-full-url=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_02.png\" data-link=\"https:\/\/www.cidademarketing.com.br\/marketing\/?attachment_id=17546\" class=\"wp-image-17546\" srcset=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_02-1024x568.png 1024w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_02-300x166.png 300w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_02-768x426.png 768w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_02-1536x852.png 1536w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_02-2048x1136.png 2048w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_02-757x420.png 757w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_02-640x355.png 640w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_02-681x378.png 681w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1024\" height=\"572\" src=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_03-1024x572.png\" alt=\"\" data-id=\"17547\" data-full-url=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_03.png\" data-link=\"https:\/\/www.cidademarketing.com.br\/marketing\/?attachment_id=17547\" class=\"wp-image-17547\" srcset=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_03-1024x572.png 1024w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_03-300x167.png 300w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_03-768x429.png 768w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_03-1536x857.png 1536w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_03-2048x1143.png 2048w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_03-752x420.png 752w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_03-640x357.png 640w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_03-681x380.png 681w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_04-1024x575.png\" alt=\"\" data-id=\"17548\" data-full-url=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_04.png\" data-link=\"https:\/\/www.cidademarketing.com.br\/marketing\/?attachment_id=17548\" class=\"wp-image-17548\" srcset=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_04-1024x575.png 1024w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_04-300x168.png 300w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_04-768x431.png 768w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_04-1536x863.png 1536w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_04-2048x1150.png 2048w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_04-748x420.png 748w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_04-640x359.png 640w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_04-681x382.png 681w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"570\" src=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_05-1024x570.png\" alt=\"\" data-id=\"17549\" data-full-url=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_05.png\" data-link=\"https:\/\/www.cidademarketing.com.br\/marketing\/?attachment_id=17549\" class=\"wp-image-17549\" srcset=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_05-1024x570.png 1024w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_05-300x167.png 300w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_05-768x428.png 768w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_05-1536x855.png 1536w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_05-2048x1140.png 2048w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_05-754x420.png 754w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_05-640x356.png 640w, https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_05-681x379.png 681w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>\u201c<em>A proposta da campanha \u00e9 resgatar as emo\u00e7\u00f5es e colocar em foco as sensa\u00e7\u00f5es positivas de carinho e de grande proximidade entre pais e filhos, intensificadas e aproximadas por do contexto delicado que estamos vivendo. \u00c9 uma forma de enaltecer os pequenos detalhes que se mostraram hoje ser o que realmente importa<\/em>\u201d, comenta Patricia Andrade, da Lew\u2019Lara\\TBWA&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m da mensagem de otimismo e carinho para comemorar o dia dos pais, o BB aproveita a oportunidade para conectar comunica\u00e7\u00e3o e os canais de atendimento. Basta apontar a c\u00e2mera do celular para o QR Code dispon\u00edvel no filme para ser automaticamente redirecionado para o whatsapp, respondido por intelig\u00eancia artificial, j\u00e1 programada para te enviar o arquivo do filme para que o p\u00fablico possa compartilhar com a fam\u00edlia.&nbsp;<\/p>\n\n\n\n<p>\u201c<em>O QR Code est\u00e1 sendo bastante utilizado pelas marcas na publicidade. O ineditismo est\u00e1 em permitir o compartilhamento r\u00e1pido do v\u00eddeo utilizando o Bot do Banco, no Whatsapp. \u00c9 uma a\u00e7\u00e3o integrada de m\u00eddia na TV com nossos canais digitais, que gera engajamento e ao mesmo tempo oportunidade de neg\u00f3cios em futuras a\u00e7\u00f5es comerciais e de relacionamento<\/em>\u201d, complementou Tadeu Figueir\u00f3, executivo na Dined.&nbsp;<\/p>\n\n\n\n<p>O p\u00fablico tem \u00e0 disposi\u00e7\u00e3o o whatsapp como canal de atendimento r\u00e1pido, comandado por intelig\u00eancia artificial capaz de atender quest\u00f5es de extrato, pagamento de contas, consulta de saldo e de limite de cart\u00e3o e at\u00e9 renegocia\u00e7\u00e3o de d\u00edvidas. Tamb\u00e9m est\u00e3o dispon\u00edveis atendimento via telefone, site e redes sociais do BB.&nbsp;<\/p>\n\n\n\n<p>Vale lembrar que todas as imagens\/produ\u00e7\u00e3o do filme foram feitas respeitando os protocolos de seguran\u00e7a vigentes, segundo recomenda\u00e7\u00f5es da Organiza\u00e7\u00e3o Mundial da Sa\u00fade e \u00f3rg\u00e3os respons\u00e1veis.&nbsp;<\/p>\n\n\n\n<p>Clique&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=VIXELB5iDuo\">aqui<\/a>&nbsp;e confira o filme.&nbsp;<\/p>\n\n\n\n<p><strong>FICHA T\u00c9CNICA&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ag\u00eancia<\/strong>: LEW\u2019LARA\\TBWA&nbsp;<\/p>\n\n\n\n<p><strong>Cliente<\/strong>: Banco do Brasil&nbsp;<\/p>\n\n\n\n<p><strong>Produto<\/strong>: Dia dos Pais&nbsp;<\/p>\n\n\n\n<p><strong>Dura\u00e7\u00e3o<\/strong>: 30\u201d&nbsp;<\/p>\n\n\n\n<p><strong>Chairman Grupo TBWA<\/strong>: Luiz Lara&nbsp;<\/p>\n\n\n\n<p><strong>CEO<\/strong>: Marcia Esteves&nbsp;<\/p>\n\n\n\n<p><strong>Vice-Presid\u00eancia Executiva<\/strong>: Elise Passamani, Renata Serafim,&nbsp;<\/p>\n\n\n\n<p>Sleyman Khodor, Vicente Varela, Wilson Negrini&nbsp;<\/p>\n\n\n\n<p><strong>Dire\u00e7\u00e3o de Cria\u00e7\u00e3o<\/strong>: Vinicius Miike&nbsp;<\/p>\n\n\n\n<p><strong>Dire\u00e7\u00e3o de Arte<\/strong>: Igor de S\u00e1&nbsp;<\/p>\n\n\n\n<p><strong>Reda\u00e7\u00e3o<\/strong>: Vinicius Miike, Polyana Bandeira, Guilherme Branco e Paulo Mello&nbsp;<\/p>\n\n\n\n<p><strong>Neg\u00f3cios<\/strong>: Patricia Andrade, Gil Castello Branco e Fernanda Lopes&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia<\/strong>: Samuel Haddad&nbsp;<\/p>\n\n\n\n<p><strong>M\u00eddia<\/strong>: Eduardo Shinohara, Luana Abrantes, Barbara Sousa e Marina Veloso&nbsp;<\/p>\n\n\n\n<p><strong>BI<\/strong>: Samuel Haddad&nbsp;<\/p>\n\n\n\n<p><strong>Projetos<\/strong>: Henrique Salvadori,&nbsp;<\/p>\n\n\n\n<p><strong>Produ\u00e7\u00e3o de RTV<\/strong>: Izabel Soares e Julia Menescal&nbsp;<\/p>\n\n\n\n<p><strong>Conte\u00fado<\/strong>: Samuel Haddad&nbsp;<\/p>\n\n\n\n<p><strong>Produtora de filme:&nbsp;<\/strong>Quarteto Filmes<\/p>\n\n\n\n<p><strong>Dire\u00e7\u00e3o:&nbsp;<\/strong>Ana Barcellos<\/p>\n\n\n\n<p><strong>Produ\u00e7\u00e3o Executiva:&nbsp;<\/strong>Rodrigo Moreira<\/p>\n\n\n\n<p><strong>Produ\u00e7\u00e3o:&nbsp;<\/strong>Dandara Cavalcanti<\/p>\n\n\n\n<p><strong>Montagem:&nbsp;<\/strong>Ana Barcellos<\/p>\n\n\n\n<p><strong>Finalizador:&nbsp;<\/strong>Hermano Taranto<\/p>\n\n\n\n<p><strong>Coordena\u00e7\u00e3o de P\u00f3s:&nbsp;<\/strong>Ricardo Campos<\/p>\n\n\n\n<p><strong>Finaliza\u00e7\u00e3o:&nbsp;<\/strong>Quarteto Filmes<\/p>\n\n\n\n<p><strong>Produtora de Som:&nbsp;<\/strong>S de Samba<\/p>\n\n\n\n<p><strong>Produ\u00e7\u00e3o Executiva:&nbsp;<\/strong>Meg Magro<\/p>\n\n\n\n<p><strong>Produ\u00e7\u00e3o:&nbsp;<\/strong>Pedro Caldas, Diego Guimar\u00e3es, Antonio Arruda e Flavio Gondim<\/p>\n\n\n\n<p><strong>Locu\u00e7\u00e3o:&nbsp;<\/strong>Rafael Maia<\/p>\n\n\n\n<p><strong>Trilha:&nbsp;<\/strong>Pedro Caldas<\/p>\n\n\n\n<p><strong>Aprova\u00e7\u00e3o Cliente:&nbsp;<\/strong>Cl\u00e1udia Kakinoff, Marcelo Mendon\u00e7a, Ana Carolina Castro, Gustavo Tocantins, Emerson Muzi, Thais Oliveira e Renata Barbosa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conforme o mundo navega por um \u201cnormal\u201d muito diferente, muitas das a\u00e7\u00f5es que n\u00f3s estamos nos acostumando hoje ter\u00e3o um impacto duradouro nas vidas. Entre os destaques, est\u00e3o os novos h\u00e1bitos e intera\u00e7\u00f5es familiares, ainda mais pr\u00f3xima e intensa.&nbsp; Pensando nisso, o Banco do Brasil enaltece o surgimento de nova rela\u00e7\u00e3o entre pai e filhos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17550,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6],"tags":[576,167,65,28,2935],"class_list":["post-17545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-banco-do-brasil","tag-bb","tag-campanha","tag-marketing","tag-pandemia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Banco do Brasil traz campanha de Dia dos Pais que retrata novos h\u00e1bitos das rela\u00e7\u00f5es familiares - CidadeMarketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banco do Brasil traz campanha de Dia dos Pais que retrata novos h\u00e1bitos das rela\u00e7\u00f5es familiares - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"Conforme o mundo navega por um \u201cnormal\u201d muito diferente, muitas das a\u00e7\u00f5es que n\u00f3s estamos nos acostumando hoje ter\u00e3o um impacto duradouro nas vidas. Entre os destaques, est\u00e3o os novos h\u00e1bitos e intera\u00e7\u00f5es familiares, ainda mais pr\u00f3xima e intensa.&nbsp; Pensando nisso, o Banco do Brasil enaltece o surgimento de nova rela\u00e7\u00e3o entre pai e filhos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-06T13:29:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-06T13:29:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_01-1024x571.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"571\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"Banco do Brasil traz campanha de Dia dos Pais que retrata novos h\u00e1bitos das rela\u00e7\u00f5es familiares\",\"datePublished\":\"2020-08-06T13:29:35+00:00\",\"dateModified\":\"2020-08-06T13:29:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/\"},\"wordCount\":836,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/BB-Dia-dos-Pais_01.png\",\"keywords\":[\"Banco do Brasil\",\"BB\",\"campanha\",\"marketing\",\"pandemia\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/\",\"name\":\"Banco do Brasil traz campanha de Dia dos Pais que retrata novos h\u00e1bitos das rela\u00e7\u00f5es familiares - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/BB-Dia-dos-Pais_01.png\",\"datePublished\":\"2020-08-06T13:29:35+00:00\",\"dateModified\":\"2020-08-06T13:29:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/BB-Dia-dos-Pais_01.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/BB-Dia-dos-Pais_01.png\",\"width\":2845,\"height\":1586,\"caption\":\"Reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/08\\\/06\\\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banco do Brasil traz campanha de Dia dos Pais que retrata novos h\u00e1bitos das rela\u00e7\u00f5es familiares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Banco do Brasil traz campanha de Dia dos Pais que retrata novos h\u00e1bitos das rela\u00e7\u00f5es familiares - CidadeMarketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/","og_locale":"pt_BR","og_type":"article","og_title":"Banco do Brasil traz campanha de Dia dos Pais que retrata novos h\u00e1bitos das rela\u00e7\u00f5es familiares - CidadeMarketing","og_description":"Conforme o mundo navega por um \u201cnormal\u201d muito diferente, muitas das a\u00e7\u00f5es que n\u00f3s estamos nos acostumando hoje ter\u00e3o um impacto duradouro nas vidas. Entre os destaques, est\u00e3o os novos h\u00e1bitos e intera\u00e7\u00f5es familiares, ainda mais pr\u00f3xima e intensa.&nbsp; Pensando nisso, o Banco do Brasil enaltece o surgimento de nova rela\u00e7\u00e3o entre pai e filhos [&hellip;]","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2020-08-06T13:29:35+00:00","article_modified_time":"2020-08-06T13:29:37+00:00","og_image":[{"width":1024,"height":571,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_01-1024x571.png","type":"image\/png"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"Banco do Brasil traz campanha de Dia dos Pais que retrata novos h\u00e1bitos das rela\u00e7\u00f5es familiares","datePublished":"2020-08-06T13:29:35+00:00","dateModified":"2020-08-06T13:29:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/"},"wordCount":836,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_01.png","keywords":["Banco do Brasil","BB","campanha","marketing","pandemia"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/","name":"Banco do Brasil traz campanha de Dia dos Pais que retrata novos h\u00e1bitos das rela\u00e7\u00f5es familiares - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_01.png","datePublished":"2020-08-06T13:29:35+00:00","dateModified":"2020-08-06T13:29:37+00:00","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_01.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/08\/BB-Dia-dos-Pais_01.png","width":2845,"height":1586,"caption":"Reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/08\/06\/banco-do-brasil-traz-campanha-de-dia-dos-pais-que-retrata-novos-habitos-das-relacoes-familiares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"Banco do Brasil traz campanha de Dia dos Pais que retrata novos h\u00e1bitos das rela\u00e7\u00f5es familiares"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/17545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=17545"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/17545\/revisions"}],"predecessor-version":[{"id":17551,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/17545\/revisions\/17551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/17550"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=17545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=17545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=17545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}