{"id":13824,"date":"2020-01-27T20:27:22","date_gmt":"2020-01-27T23:27:22","guid":{"rendered":"https:\/\/www.cidademarketing.com.br\/marketing\/?p=13824"},"modified":"2020-01-27T20:27:25","modified_gmt":"2020-01-27T23:27:25","slug":"empreendedor-ronald-levinsohn-morre-aos-84-anos","status":"publish","type":"post","link":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/","title":{"rendered":"Empreendedor Ronald Levinsohn morre aos 84 anos"},"content":{"rendered":"\n<p>NOTA\nDE FALECIMENTO<\/p>\n\n\n\n<p>Com\nimenso pesar, o Colinas Shopping e familiares comunicam a morte do empres\u00e1rio e\nfilantropo Ronald Guimar\u00e3es Levinsohn. Aos 84 anos, ele morreu no Rio de\nJaneiro nesta segunda-feira (27), \u00e0s 8h25, no Hospital Copa Star, por fal\u00eancia\nm\u00faltipla de \u00f3rg\u00e3os.<\/p>\n\n\n\n<p>O\nvel\u00f3rio ser\u00e1 realizado no Memorial do Carmo, no Caju, Rio de Janeiro, nesta\nter\u00e7a-feira (28), a partir das 10h. A crema\u00e7\u00e3o ser\u00e1 \u00e0s 13h.<\/p>\n\n\n\n<p>Nascido\nem 9 de outubro de 1935 na cidade de Rio Grande (RS), Levinsohn foi um dos\nprincipais empres\u00e1rios e investidores do mercado financeiro no Brasil, nos\nramos imobili\u00e1rio, educacional e do agroneg\u00f3cio.<\/p>\n\n\n\n<p>Aos\n17 anos, Levinsohn se mudou para os Estados Unidos, onde estudou Finan\u00e7as. Ap\u00f3s\na gradua\u00e7\u00e3o, j\u00e1 noivo de Henriqueta, com quem permaneceu casado at\u00e9 a morte,\nRonald come\u00e7ou a investir na Bolsa de Valores de Nova York.&nbsp;<\/p>\n\n\n\n<p>Ao\nretornar ao Brasil, tamb\u00e9m manteve investimentos no mercado financeiro e\nimobili\u00e1rio. Em 1975, associado a Rodman Rockfeller, Levinsohn chegou a S\u00e3o\nJos\u00e9 dos Campos, quando planejou o empreendimento imobili\u00e1rio Cidade Vista\nVerde, na zona leste da cidade. Depois, vieram outros dois condom\u00ednios, Jardim\nColinas e Jardim do Golfe, e o Colinas Shopping \u2013 que foi o primeiro shopping\nda cidade planejado como um mall desde a concep\u00e7\u00e3o do projeto, antes da\nconstru\u00e7\u00e3o.<\/p>\n\n\n\n<p>Levinsohn\ntamb\u00e9m foi presidente do Centro Universit\u00e1rio da Cidade do Rio de Janeiro,\ninstitui\u00e7\u00e3o educacional e filantr\u00f3pica fundada em 1969 e que durante d\u00e9cadas\nfoi um exemplo de excel\u00eancia em ensino superior. Com diversos cursos de\ngradua\u00e7\u00e3o nas \u00e1reas de humanas, exatas e biol\u00f3gicas, al\u00e9m de p\u00f3s-gradua\u00e7\u00f5es\nlato sensu e stricto sensu, foi a terceira maior universidade privada do Rio de\nJaneiro e chegou a ter 35 mil alunos matriculados no mesmo ano.<\/p>\n\n\n\n<p>No\nagroneg\u00f3cio, \u00e9 reconhecido em Formosa do Rio Preto, no Oeste da Bahia, pela\ncontribui\u00e7\u00e3o ao progresso da cidade, com investimentos em infraestrutura, como\nestradas, tratamento de esgoto e energia el\u00e9trica, e pelo trabalho \u00e0 frente do\nCondom\u00ednio Cachoeira do Estrondo, um dos maiores produtores de soja, milho e\nalgod\u00e3o do pa\u00eds. Em 2014, Levinsohn produziu o livro \u201cFormosa do Rio Preto \u2013\nOntem e Hoje\u201d, distribu\u00eddo aos moradores da cidade.&nbsp;<\/p>\n\n\n\n<p>Levinsohn\nestava internado h\u00e1 11 dias, diagnosticado com fibrose pulmonar. Ele deixa esposa,\nHenriqueta, duas filhas, Cl\u00e1udia e Priscilla, dois netos e tr\u00eas bisnetos.\n\nNeste momento, a fam\u00edlia se une para rememorar a\ngrandeza e as conquistas que comp\u00f5em a hist\u00f3ria deste grande homem, filantropo\ne empres\u00e1rio, e prestar homenagens ao amado e querido pai, marido e av\u00f4 que\nRonald Levinsohn sempre foi e sempre ser\u00e1, agora, nas lembran\u00e7as de uma vida\nplenamente vivida\n\n\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTA DE FALECIMENTO Com imenso pesar, o Colinas Shopping e familiares comunicam a morte do empres\u00e1rio e filantropo Ronald Guimar\u00e3es Levinsohn. Aos 84 anos, ele morreu no Rio de Janeiro nesta segunda-feira (27), \u00e0s 8h25, no Hospital Copa Star, por fal\u00eancia m\u00faltipla de \u00f3rg\u00e3os. O vel\u00f3rio ser\u00e1 realizado no Memorial do Carmo, no Caju, Rio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13825,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6],"tags":[741,28],"class_list":["post-13824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-empreendedor","tag-marketing"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empreendedor Ronald Levinsohn morre aos 84 anos - CidadeMarketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empreendedor Ronald Levinsohn morre aos 84 anos - CidadeMarketing\" \/>\n<meta property=\"og:description\" content=\"NOTA DE FALECIMENTO Com imenso pesar, o Colinas Shopping e familiares comunicam a morte do empres\u00e1rio e filantropo Ronald Guimar\u00e3es Levinsohn. Aos 84 anos, ele morreu no Rio de Janeiro nesta segunda-feira (27), \u00e0s 8h25, no Hospital Copa Star, por fal\u00eancia m\u00faltipla de \u00f3rg\u00e3os. O vel\u00f3rio ser\u00e1 realizado no Memorial do Carmo, no Caju, Rio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"CidadeMarketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcidademarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/thalesbrandao\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-27T23:27:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-27T23:27:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/ronald_levinsohn.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"530\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thales Brand\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/www.twitter.com\/thalesbrandao\" \/>\n<meta name=\"twitter:site\" content=\"@CidadeMarketing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thales Brand\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/\"},\"author\":{\"name\":\"Thales Brand\u00e3o\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\"},\"headline\":\"Empreendedor Ronald Levinsohn morre aos 84 anos\",\"datePublished\":\"2020-01-27T23:27:22+00:00\",\"dateModified\":\"2020-01-27T23:27:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/\"},\"wordCount\":471,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ronald_levinsohn.jpeg\",\"keywords\":[\"empreendedor\",\"marketing\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/\",\"name\":\"Empreendedor Ronald Levinsohn morre aos 84 anos - CidadeMarketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ronald_levinsohn.jpeg\",\"datePublished\":\"2020-01-27T23:27:22+00:00\",\"dateModified\":\"2020-01-27T23:27:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ronald_levinsohn.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ronald_levinsohn.jpeg\",\"width\":530,\"height\":555,\"caption\":\"Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/2020\\\/01\\\/27\\\/empreendedor-ronald-levinsohn-morre-aos-84-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empreendedor Ronald Levinsohn morre aos 84 anos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#website\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"name\":\"CidadeMarketing\",\"description\":\"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\"},\"alternateName\":\"CidadeMarketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#organization\",\"name\":\"CidadeMarketing\",\"alternateName\":\"CidadeMarketing\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/cidademarketing_marca_mobile.png\",\"width\":230,\"height\":92,\"caption\":\"CidadeMarketing\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcidademarketing\",\"https:\\\/\\\/x.com\\\/CidadeMarketing\",\"https:\\\/\\\/www.instagram.com\\\/cidademarketing\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/#\\\/schema\\\/person\\\/02daff9f18bd9378c9e01eb6b2db155f\",\"name\":\"Thales Brand\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g\",\"caption\":\"Thales Brand\u00e3o\"},\"description\":\"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao\",\"sameAs\":[\"http:\\\/\\\/www.mandacaru.com.br\",\"https:\\\/\\\/www.facebook.com\\\/thalesbrandao\",\"http:\\\/\\\/www.instagram.com.br\\\/thalesbrandaoferreira\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thales-brand\u00e3o-3948609\\\/\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/www.twitter.com\\\/thalesbrandao\"],\"url\":\"https:\\\/\\\/www.cidademarketing.com.br\\\/marketing\\\/author\\\/thalesbrandao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empreendedor Ronald Levinsohn morre aos 84 anos - CidadeMarketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"Empreendedor Ronald Levinsohn morre aos 84 anos - CidadeMarketing","og_description":"NOTA DE FALECIMENTO Com imenso pesar, o Colinas Shopping e familiares comunicam a morte do empres\u00e1rio e filantropo Ronald Guimar\u00e3es Levinsohn. Aos 84 anos, ele morreu no Rio de Janeiro nesta segunda-feira (27), \u00e0s 8h25, no Hospital Copa Star, por fal\u00eancia m\u00faltipla de \u00f3rg\u00e3os. O vel\u00f3rio ser\u00e1 realizado no Memorial do Carmo, no Caju, Rio [&hellip;]","og_url":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/","og_site_name":"CidadeMarketing","article_publisher":"https:\/\/www.facebook.com\/portalcidademarketing","article_author":"https:\/\/www.facebook.com\/thalesbrandao","article_published_time":"2020-01-27T23:27:22+00:00","article_modified_time":"2020-01-27T23:27:25+00:00","og_image":[{"width":530,"height":555,"url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/ronald_levinsohn.jpeg","type":"image\/jpeg"}],"author":"Thales Brand\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/www.twitter.com\/thalesbrandao","twitter_site":"@CidadeMarketing","twitter_misc":{"Escrito por":"Thales Brand\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/#article","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/"},"author":{"name":"Thales Brand\u00e3o","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f"},"headline":"Empreendedor Ronald Levinsohn morre aos 84 anos","datePublished":"2020-01-27T23:27:22+00:00","dateModified":"2020-01-27T23:27:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/"},"wordCount":471,"commentCount":0,"publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/ronald_levinsohn.jpeg","keywords":["empreendedor","marketing"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/","name":"Empreendedor Ronald Levinsohn morre aos 84 anos - CidadeMarketing","isPartOf":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/#primaryimage"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/ronald_levinsohn.jpeg","datePublished":"2020-01-27T23:27:22+00:00","dateModified":"2020-01-27T23:27:25+00:00","breadcrumb":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/#primaryimage","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/ronald_levinsohn.jpeg","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/ronald_levinsohn.jpeg","width":530,"height":555,"caption":"Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/2020\/01\/27\/empreendedor-ronald-levinsohn-morre-aos-84-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cidademarketing.com.br\/marketing\/"},{"@type":"ListItem","position":2,"name":"Empreendedor Ronald Levinsohn morre aos 84 anos"}]},{"@type":"WebSite","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#website","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","name":"CidadeMarketing","description":"Somos um ve\u00edculo de comunica\u00e7\u00e3o de destaque no Brasil, reconhecido por conte\u00fados nos segmentos de marketing, empreendedorismo e inova\u00e7\u00e3o.","publisher":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization"},"alternateName":"CidadeMarketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cidademarketing.com.br\/marketing\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#organization","name":"CidadeMarketing","alternateName":"CidadeMarketing","url":"https:\/\/www.cidademarketing.com.br\/marketing\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/","url":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","contentUrl":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-content\/uploads\/2020\/01\/cidademarketing_marca_mobile.png","width":230,"height":92,"caption":"CidadeMarketing"},"image":{"@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcidademarketing","https:\/\/x.com\/CidadeMarketing","https:\/\/www.instagram.com\/cidademarketing\/"]},{"@type":"Person","@id":"https:\/\/www.cidademarketing.com.br\/marketing\/#\/schema\/person\/02daff9f18bd9378c9e01eb6b2db155f","name":"Thales Brand\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca3206950207cc3cb48feec56a8a7898741ab725c368d99d5d7a5a50aab80c6?s=96&d=mm&r=g","caption":"Thales Brand\u00e3o"},"description":"Editor Executivo do Portal CidadeMarketing.com.br &gt; Mestre em Comunica\u00e7\u00e3o e Sociedade pela Universidade Federal de Sergipe. Possui MBA Executivo em Administra\u00e7\u00e3o com \u00eanfase em Marketing pela Funda\u00e7\u00e3o Get\u00falio Vargas - Rio de Janeiro. Consultor, Palestrante e Pesquisador sobre Empreendedorismo, Marketing, Redes Sociais e Neg\u00f3cios Digitais. Professor, Palestrante TedxTalks e Campus Party. Twitter: @ThalesBrandao","sameAs":["http:\/\/www.mandacaru.com.br","https:\/\/www.facebook.com\/thalesbrandao","http:\/\/www.instagram.com.br\/thalesbrandaoferreira","https:\/\/www.linkedin.com\/in\/thales-brand\u00e3o-3948609\/","https:\/\/x.com\/http:\/\/www.twitter.com\/thalesbrandao"],"url":"https:\/\/www.cidademarketing.com.br\/marketing\/author\/thalesbrandao\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/13824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/comments?post=13824"}],"version-history":[{"count":1,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/13824\/revisions"}],"predecessor-version":[{"id":13826,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/posts\/13824\/revisions\/13826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media\/13825"}],"wp:attachment":[{"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/media?parent=13824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/categories?post=13824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cidademarketing.com.br\/marketing\/wp-json\/wp\/v2\/tags?post=13824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}